{"id":62865,"date":"2021-01-01T18:44:13","date_gmt":"2021-01-01T17:44:13","guid":{"rendered":"https:\/\/www.razorman.net\/reviewshardware\/?p=62865"},"modified":"2021-01-01T18:44:13","modified_gmt":"2021-01-01T17:44:13","slug":"review-msi-geforce-rtx-2080-ti-gaming-x-trio","status":"publish","type":"post","link":"https:\/\/www.razorman.net\/reviewshardware\/review-msi-geforce-rtx-2080-ti-gaming-x-trio\/","title":{"rendered":"Review MSI Geforce RTX 2080 Ti Gaming X Trio"},"content":{"rendered":"<p>Hoy os traemos la <strong>review<\/strong> de la que es la gr\u00e1fica m\u00e1s potente de la gama RTX 2080 de <strong>MSI<\/strong>, con el modelo <strong>Geforce RTX 2080 TI Gaming X Trio<\/strong>,\u00a0 con 11 GB GDDR6 y una velocidad Boost de 1755 Mhz.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/asset.msi.com\/resize\/image\/global\/product\/product_1_20180919185540_5ba22b2ce7ec4.png62405b38c58fe0f07fcef2367d8a9ba1\/1024.png\" alt=\"\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p>Much\u00edsimas gracias a<strong> MSI<\/strong> por enviarnos la tarjeta gr\u00e1fica <strong>MSI Geforce RTX 2080 Ti Gaming X Trio<\/strong> para la <strong>review<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full aligncenter\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/logo-msi.jpg\" width=\"550\" height=\"395\" alt=\"\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>MSI GEFORCE RTX 2080 TI GAMING X TRIO: CARACTERISTICAS TECNICAS<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\">MOTOR GRAFICO Y MEMORIA<\/td>\n<td style=\"width: 50%;\">NVIDIA\u00ae GeForce\u00ae RTX 2080 Ti , 11GB GDDR6<\/p>\n<p>PCI Express x16 3.0<\/p>\n<p>INTERFAZ MEMORIA: 352 bits<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">VELOCIDAD RELOJ NUCLEO<\/td>\n<td style=\"width: 50%;\">1755 MHz \/ 1350 MHz<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">CANTIDAD MONITORES SOPORTADOS Y RESOLUCION<\/td>\n<td style=\"width: 50%;\">4<\/p>\n<p>7680 x 4320<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">TECNOLOGIA MULTI-GPU<\/td>\n<td style=\"width: 50%;\">NVIDIA\u00ae NVLINK&#x2122; (SLI-Ready), 2-way<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">CONSUMO<\/td>\n<td style=\"width: 50%;\">300W (FUENTE ALIMENTACION 650W RECOMENDADA)<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">SALIDAS<\/td>\n<td style=\"width: 50%;\">DisplayPort x 3 (v1.4) \/ HDMI 2.0b x 1 \/ USB Type-C x1<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">CONECTORES ALIMENTACION<\/td>\n<td style=\"width: 50%;\">8-pin x 2, 6-pin x 1<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">DIMENSIONES<\/td>\n<td style=\"width: 50%;\">327 x 140 x 55.6 mm<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">PESO<\/td>\n<td style=\"width: 50%;\">1582 Gr<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>[nextpage title= \u00abMSI GEFORCE RTX 2080 TI GAMING X TRIO: UNBOXING Y ACCESORIOS\u00bb]<\/p>\n<p>La tarjeta se presenta en una caja de atractivo colorido, donde a trav\u00e9s de la misma encontramos abundante informaci\u00f3n t\u00e9cnica y varias im\u00e1genes de la tarjeta.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-62867\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-1.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-1.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-1-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-1-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/> <img decoding=\"async\" class=\"aligncenter size-full wp-image-62868\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-2.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-2.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-2-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-2-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Al retirar la caja comprobamos que la tarjeta viene muy bien protegida: colocada sobre una base de porexp\u00e1n negra y protegida por una bolsa anti-est\u00e1tica. Parte de los accesorios vienen tambi\u00e9n dispuestos en esa base de porexp\u00e1n y tambi\u00e9n dentro de un sobre negro con el logo de MSI.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62869\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-3.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-3.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-3-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-3-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Los accesorios incluyen variado material de m\u00e1rketing, un adaptador de corriente de 8 pines y un brazo met\u00e1lico para sujetarla a la caja, pues recordemos que la tarjeta pesa 1582 gramos.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62870\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-4.jpg\" alt=\"\" width=\"790\" height=\"768\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-4.jpg 790w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-4-300x292.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-4-768x747.jpg 768w\" sizes=\"(max-width: 790px) 100vw, 790px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[nextpage title= \u00abMSI GEFORCE RTX 2080 TI GAMING X TRIO: DISE\u00d1O\u00bb]<\/p>\n<p>El dise\u00f1o es realmente espectacular , gracias al sistema de refrigeraci\u00f3n Tri-Forz compuesto por 3 ventiladores Torx 3.0 incluidos en una carcasa de pl\u00e1stico de atrevido dise\u00f1o.<\/p>\n<p>En esta carcasa tambi\u00e9n se incluyen 4 leds entre los ventiladores laterales y el central. En cuanto a dimensiones, \u00e9stas son de 327 x 140 x 55.6 mm para un peso de 1582 gramos.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62872\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-5.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-5.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-5-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-5-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>En la zona delantera cuenta con estas conexiones:<\/p>\n<ul>\n<li>3X DisplayPort con una salida de video 8K @ 60 Hz<\/li>\n<li>1X Salida HDMI 2.0b para 4K @ 60 Hz<\/li>\n<li>Puerto USB Type-C.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62873\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-7.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-7.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-7-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-7-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Contando como parte activa de la refrigeraci\u00f3n encontramos un blackplate met\u00e1lico con el logo de MSI.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62874\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-8.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-8.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-8-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-8-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>El sistema de refrigeraci\u00f3n como vemos est\u00e1 muy bien dimensionado con un generoso radiador que recorre todo el PCB de la gr\u00e1fica y con varios heatpipes encargados de transportar el calor por este radiador.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62875\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-9.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-9.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-9-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-9-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La conexi\u00f3n a placa base se realiza mediante un conector PCI Express x16 3.0<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62876\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-10.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-10.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-10-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-10-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La zona trasera est\u00e1 parcialmente tapada por la carcasa de pl\u00e1stico de los ventiladores y nos dejan ver parte los 5 heatpipes encargados de refrigerar la gr\u00e1fica.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62877\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-11.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-11.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-11-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-11-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Vista superior: encontramos en la zona superior de la carcasa de pl\u00e1stico el logo del fabricante, el logo de MSI y la gama a la cual pertenece la gr\u00e1fica, dejando ver tambi\u00e9n una buena parte del radiador de la gr\u00e1fica.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62878\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-12.jpg\" alt=\"\" width=\"1024\" height=\"399\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-12.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-12-300x117.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-12-768x299.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Para alimentar a esta \u00abbestia\u00bb contamos con 2X conectores de 8 pines y un conector de 6 pines, necesarios pues el TDP de la gr\u00e1fica asciende a 300W y el fabricante recomienda al menos una fuente de alimentaci\u00f3n de 650W.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62879\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-13.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-13.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-13-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-13-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[nextpage title= \u00abMSI GEFORCE RTX 2080 TI GAMING X TRIO: PCB INTERIOR\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p>Acceder al PCB interior es un poco laborioso por la cantidad de tornillos que hay que retirar: nada menos que 18 tornillos .<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62881\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-14.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-14.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-14-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-14-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62882\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-15.jpg\" alt=\"\" width=\"1024\" height=\"502\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-15.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-15-300x147.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-15-768x377.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Esta versi\u00f3n TI est\u00e1 montada sobre el chip gr\u00e1fico TU102 de nVidia, realizado con proceso de fabricaci\u00f3n FinFET de 12nm.<\/p>\n<p>Posee un total de 4352 CUDA Cores, y 272 unidades de textura, con 544 tensor cores y 68 RT Cores. La frecuencia base de reloj es de 1350 Mhz y en modo Boost alcanza los 1755 Mhz.<\/p>\n<p>En cuanto a memoria, est\u00e1 muy bien servida con nada menos que 11 GB GDDR6 en un bus de 352 bits. Su TDP es de 300W. Posee un potente VRM de 11+2 fases.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62883\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-16.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-16.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-16-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-16-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62884\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-17.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-17.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-17-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-17-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62885\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-18.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-18.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-18-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-18-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62886\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-19.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-19.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-19-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-19-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>El sistema de refrigeraci\u00f3n est\u00e1 muy bien dimensionado y recorre como vemos todo el PCB de la tarjeta, con un radiador de aluminio dividido en dos mitades y recorridos por 5 heatpipes de buen grosor comunicando las dos mitades del radiador.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62887\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-20.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-20.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-20-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-20-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Esta zona del radiador incluye varias tiras de pads termicos para refrigerar las memorias y VRM<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62888\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-21.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-21.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-21-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-21-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Detalle del z\u00f3calo del radiador en contacto con el core de la gr\u00e1fica, bien dimensionado y de cobre niquelado.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62890\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-23.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-23.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-23-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-23-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[nextpage title= \u00abMSI GEFORCE RTX 2080 TI GAMING X TRIO: ILUMINACION\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p>Realmente espectacular y que podremos configurar desde Dragon Control Center:<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62901\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-26-1.jpg\" alt=\"\" width=\"1024\" height=\"566\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-26-1.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-26-1-300x166.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-26-1-768x425.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62904\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-29-1.jpg\" alt=\"\" width=\"1024\" height=\"631\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-29-1.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-29-1-300x185.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-29-1-768x473.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62905\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-31-1.jpg\" alt=\"\" width=\"1024\" height=\"768\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-31-1.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-31-1-300x225.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-31-1-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<br \/>\n[nextpage title= \u00abMSI GEFORCE RTX 2080 TI GAMING X TRIO: PRUEBAS DE RENDIMIENTO\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62891\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-24.jpg\" alt=\"\" width=\"1024\" height=\"627\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-24.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-24-300x184.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-24-768x470.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Este es el setup empleado:<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62906\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.326-4.jpg\" alt=\"\" width=\"709\" height=\"302\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.326-4.jpg 709w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.326-4-300x128.jpg 300w\" sizes=\"(max-width: 709px) 100vw, 709px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Una captura de GPU-Z:<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62907\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.18-39.jpg\" alt=\"\" width=\"600\" height=\"768\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.18-39.jpg 600w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.18-39-234x300.jpg 234w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62908\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.19-37.jpg\" alt=\"\" width=\"589\" height=\"768\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.19-37.jpg 589w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.19-37-230x300.jpg 230w\" sizes=\"(max-width: 589px) 100vw, 589px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[box type=\u00bbshadow\u00bb align=\u00bbaligncenter\u00bb class=\u00bb\u00bb width=\u00bb\u00bb]TESTS SINTETICOS[\/box]<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>VR-MARK ORANGE ROOM<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62909\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.20-25.jpg\" alt=\"\" width=\"1024\" height=\"552\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.20-25.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.20-25-300x162.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.20-25-768x414.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62917\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.327-5.jpg\" alt=\"\" width=\"697\" height=\"697\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.327-5.jpg 697w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.327-5-300x300.jpg 300w\" sizes=\"(max-width: 697px) 100vw, 697px\" \/><\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>PCMARK 10<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62919\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.328-3.jpg\" alt=\"\" width=\"699\" height=\"745\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.328-3.jpg 699w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.328-3-281x300.jpg 281w\" sizes=\"(max-width: 699px) 100vw, 699px\" \/><\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>3DMARK<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62910\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.21-27.jpg\" alt=\"\" width=\"1024\" height=\"682\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.21-27.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.21-27-300x200.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.21-27-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62911\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.22-28.jpg\" alt=\"\" width=\"1024\" height=\"617\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.22-28.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.22-28-300x181.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.22-28-768x463.jpg 768w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.22-28-780x470.jpg 780w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62912\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.23-25.jpg\" alt=\"\" width=\"1024\" height=\"616\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.23-25.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.23-25-300x180.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.23-25-768x462.jpg 768w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.23-25-780x470.jpg 780w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62920\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.329-4.jpg\" alt=\"\" width=\"698\" height=\"951\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.329-4.jpg 698w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.329-4-220x300.jpg 220w\" sizes=\"(max-width: 698px) 100vw, 698px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Excelente rendimiento, aunque no muy alejado de la 2080 Supero como era de esperar.<\/p>\n<p>&nbsp;<\/p>\n<p>[box type=\u00bbshadow\u00bb align=\u00bbaligncenter\u00bb class=\u00bb\u00bb width=\u00bb\u00bb]JUEGOS[\/box]<\/p>\n<p>&nbsp;<\/p>\n<p>[box type=\u00bbinfo\u00bb align=\u00bbaligncenter\u00bb class=\u00bb\u00bb width=\u00bb\u00bb]ASSASIN\u00b4S CREED ODDISSEY CALIDAD MUY ALTA[\/box]<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62923\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.330-5.jpg\" alt=\"\" width=\"692\" height=\"893\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.330-5.jpg 692w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.330-5-232x300.jpg 232w\" sizes=\"(max-width: 692px) 100vw, 692px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62924\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.331-5.jpg\" alt=\"\" width=\"691\" height=\"880\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.331-5.jpg 691w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.331-5-236x300.jpg 236w\" sizes=\"(max-width: 691px) 100vw, 691px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[box type=\u00bbinfo\u00bb align=\u00bbaligncenter\u00bb class=\u00bb\u00bb width=\u00bb\u00bb]CHERNOBYLITE: SETTINGS HIGH[\/box]<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62925\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.332-5.jpg\" alt=\"\" width=\"693\" height=\"921\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.332-5.jpg 693w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.332-5-226x300.jpg 226w\" sizes=\"(max-width: 693px) 100vw, 693px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62926\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.333-5.jpg\" alt=\"\" width=\"698\" height=\"965\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.333-5.jpg 698w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.333-5-217x300.jpg 217w\" sizes=\"(max-width: 698px) 100vw, 698px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[box type=\u00bbinfo\u00bb align=\u00bbaligncenter\u00bb class=\u00bb\u00bb width=\u00bb\u00bb]WORLD WAR Z 2560X1440 \u2013 ALTO[\/box]<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62927\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.334-4.jpg\" alt=\"\" width=\"695\" height=\"980\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.334-4.jpg 695w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.334-4-213x300.jpg 213w\" sizes=\"(max-width: 695px) 100vw, 695px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[box type=\u00bbinfo\u00bb align=\u00bbaligncenter\u00bb class=\u00bb\u00bb width=\u00bb\u00bb]GEAR TACTICS \u2013 ALTO \u2013[\/box]<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62928\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.335-5.jpg\" alt=\"\" width=\"699\" height=\"923\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.335-5.jpg 699w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.335-5-227x300.jpg 227w\" sizes=\"(max-width: 699px) 100vw, 699px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62929\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.336-3.jpg\" alt=\"\" width=\"693\" height=\"995\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.336-3.jpg 693w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.336-3-209x300.jpg 209w\" sizes=\"(max-width: 693px) 100vw, 693px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[box type=\u00bbinfo\u00bb align=\u00bbaligncenter\u00bb class=\u00bb\u00bb width=\u00bb\u00bb]DEUS EX MANKIND DIVIDED \u2013 CALIDAD ALTA[\/box]<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62931\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.337-5.jpg\" alt=\"\" width=\"696\" height=\"980\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.337-5.jpg 696w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.337-5-213x300.jpg 213w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62932\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.338-4.jpg\" alt=\"\" width=\"699\" height=\"904\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.338-4.jpg 699w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.338-4-232x300.jpg 232w\" sizes=\"(max-width: 699px) 100vw, 699px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[box type=\u00bbinfo\u00bb align=\u00bbaligncenter\u00bb class=\u00bb\u00bb width=\u00bb\u00bb]HORIZON ZERO DAWN: CALIDAD ULTRA[\/box]<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62934\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.339-4.jpg\" alt=\"\" width=\"694\" height=\"956\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.339-4.jpg 694w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.339-4-218x300.jpg 218w\" sizes=\"(max-width: 694px) 100vw, 694px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62935\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.340-5.jpg\" alt=\"\" width=\"694\" height=\"955\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.340-5.jpg 694w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.340-5-218x300.jpg 218w\" sizes=\"(max-width: 694px) 100vw, 694px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[box type=\u00bbinfo\u00bb align=\u00bbaligncenter\u00bb class=\u00bb\u00bb width=\u00bb\u00bb]TOTAL WAR THREE KINGDOMS \u2013 CALIDAD ULTRA[\/box]<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62937\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.341-6.jpg\" alt=\"\" width=\"699\" height=\"983\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.341-6.jpg 699w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.341-6-213x300.jpg 213w\" sizes=\"(max-width: 699px) 100vw, 699px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62938\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.342-4.jpg\" alt=\"\" width=\"691\" height=\"959\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.342-4.jpg 691w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.342-4-216x300.jpg 216w\" sizes=\"(max-width: 691px) 100vw, 691px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[box type=\u00bbinfo\u00bb align=\u00bbaligncenter\u00bb class=\u00bb\u00bb width=\u00bb\u00bb]TOM CLANCY\u00b4S GHOST RECON \u2013 CALIDAD ALTA[\/box]<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62940\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.343-5.jpg\" alt=\"\" width=\"692\" height=\"967\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.343-5.jpg 692w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.343-5-215x300.jpg 215w\" sizes=\"(max-width: 692px) 100vw, 692px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62941\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.344-4.jpg\" alt=\"\" width=\"689\" height=\"970\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.344-4.jpg 689w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.344-4-213x300.jpg 213w\" sizes=\"(max-width: 689px) 100vw, 689px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[box type=\u00bbinfo\u00bb align=\u00bbaligncenter\u00bb class=\u00bb\u00bb width=\u00bb\u00bb]METRO EXODUS \u2013 CALIDAD ULTRA[\/box]<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62943\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.345-5.jpg\" alt=\"\" width=\"723\" height=\"921\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.345-5.jpg 723w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.345-5-236x300.jpg 236w\" sizes=\"(max-width: 723px) 100vw, 723px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62944\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.346-5.jpg\" alt=\"\" width=\"694\" height=\"978\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.346-5.jpg 694w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.346-5-213x300.jpg 213w\" sizes=\"(max-width: 694px) 100vw, 694px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[box type=\u00bbinfo\u00bb align=\u00bbaligncenter\u00bb class=\u00bb\u00bb width=\u00bb\u00bb]SHADOW OF THE TOMB RAIDER \u2013 HIGH[\/box]<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62946\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.347-5.jpg\" alt=\"\" width=\"685\" height=\"985\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.347-5.jpg 685w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.347-5-209x300.jpg 209w\" sizes=\"(max-width: 685px) 100vw, 685px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62947\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.348-4.jpg\" alt=\"\" width=\"690\" height=\"957\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.348-4.jpg 690w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.348-4-216x300.jpg 216w\" sizes=\"(max-width: 690px) 100vw, 690px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[box type=\u00bbinfo\u00bb align=\u00bbaligncenter\u00bb class=\u00bb\u00bb width=\u00bb\u00bb]MAFIA 2 DEFINITIVE EDITION[\/box]<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62949\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.349-4.jpg\" alt=\"\" width=\"697\" height=\"807\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.349-4.jpg 697w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.349-4-259x300.jpg 259w\" sizes=\"(max-width: 697px) 100vw, 697px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62950\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.350-6.jpg\" alt=\"\" width=\"698\" height=\"785\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.350-6.jpg 698w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.350-6-267x300.jpg 267w\" sizes=\"(max-width: 698px) 100vw, 698px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La gr\u00e1fica MSI GEFORCE RTX 2080 TI GAMING X TRIO se muestra superior a su hermana MSI Geforce RTX 2080 Super en todas las pruebas como esper\u00e1bamos, con un gran rendimiento que nos permite jugar a 2K en modo alto- muy alto sin problemas.<\/p>\n<p>&nbsp;<\/p>\n<p>[nextpage title= \u00abMSI GEFORCE RTX 2080 TI GAMING X TRIO:CONSUMO Y TEMPERATURAS\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p>La gr\u00e1fica tiene un TDP de 300W, por lo que esperamos un consumo realmente elevado, pero acompa\u00f1ado de unas buenas temperaturas gracias a su sistema de refrigeraci\u00f3n de 3 ventiladores.<\/p>\n<p>Para medir la temperatura y voltaje empleamos el software HWINFO, tomando nota de estos valores en IDLE y FULL.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62952\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.7-53.jpg\" alt=\"\" width=\"514\" height=\"768\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.7-53.jpg 514w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.7-53-201x300.jpg 201w\" sizes=\"(max-width: 514px) 100vw, 514px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Para estresar la gr\u00e1fica empleamos FURMARK que ejecutamos durante 30 minutos consecutivos. Estos han sido los resultados:<\/p>\n<p>&nbsp;<\/p>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\"><\/td>\n<td style=\"width: 50%;\">MSI GEFORCE RTX 2080 TI GAMING X TRIO<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">CONSUMO EN REPOSO\/FULL<\/td>\n<td style=\"width: 50%;\">27,779W &#8211; 311W<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">TEMPERATURA EN REPOSO\/FULL<\/td>\n<td style=\"width: 50%;\">31\u00baC &#8211; 71\u00baC<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>El valor de consumo m\u00e1ximo ha sido de 311W por lo que si no quieres tener problemas con tu configuraci\u00f3n, te recomendamos al menos una fuente de 650W.<\/p>\n<p>Las temperaturas han sido muy correctas, y todo ello con un buen silencio de funcionamiento. El sistema de refrigeraci\u00f3n Tri-Forz ha realizado un gran trabajo.<\/p>\n<p>En cuanto a overclock, con MSI Afterburner, pudimos subir el core de la gr\u00e1fica +150 Mhz y la memoria +800 Mhz<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62954\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.24-21.jpg\" alt=\"\" width=\"1024\" height=\"715\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.24-21.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.24-21-300x209.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.24-21-768x536.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62956\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.26-18.jpg\" alt=\"\" width=\"1024\" height=\"691\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.26-18.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.26-18-300x202.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.26-18-768x518.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\"><\/td>\n<td style=\"width: 50%;\">MSI GEFORCE RTX 2080 TI GAMING X TRIO + RYZEN 7 3700X<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">3DMARK TIME SPY &#8211; SERIE \/ OC<\/td>\n<td style=\"width: 50%;\">13480\/14166<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">RISE OF THE TOMB RAIDER FULL HD<\/td>\n<td style=\"width: 50%;\">156\/208\/318 &#8211; SERIE<\/p>\n<p>158\/211\/320 &#8211; OC<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>[nextpage title= \u00abMSI GEFORCE RTX 2080 TI GAMING X TRIO: CONCLUSIONES FINALES Y PUNTUACION\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62902\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-27-1.jpg\" alt=\"\" width=\"1024\" height=\"555\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-27-1.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-27-1-300x163.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-2080-TI-GAMING-X-TRIO-27-1-768x416.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Con respecto a la version 2080 Super previamente analizada, encontramos ahora 11 GB de memoria GDDR6 &#8211; vs 8 GB GDDR6 &#8211; , lo que se traduce aproximadamente en un 25% m\u00e1s de prestaciones en FULL HD y entre el 40-50% m\u00e1s en 2K, eso s\u00ed con un mayor consumo energ\u00e9tico pero reflejado en unas mayores prestaciones pero manteniendo un nivel sonoro baj\u00edsimo.<\/p>\n<p>Este modelo TI te permitir\u00e1 jugar en niveles alto-ultra con una gran fluidez &#8211; acompa\u00f1ado de un buen procesador como ha sido el 5600X, un pepino en juegos &#8211; por supuesto en FULL HD como en 2K, y si posees un monitor de mayor resoluci\u00f3n, te permitir\u00e1 jugar a 4K con niveles bajos-medios de detalle de forma aceptable. Sobretodo en FULL HD, el procesador puede ser un cuello de botella, como hemos visto con una mejora de prestaciones rese\u00f1able al emplear la gr\u00e1fica con un Ryzen 7 3700X o un Ryzen 5 5600X.<\/p>\n<p>La est\u00e9tica es sencillamente brutal, realmente es una de las gr\u00e1ficas m\u00e1s bonitas del mercado &#8211; dejando de lado las actuales 6XXX de AMD y RTX 3XXX de nVidia, con una iluminaci\u00f3n efectiva y muy controlable desde Dragon Center.<\/p>\n<p>Ten\u00edamos un poco de miedo a la hora de exprimir al m\u00e1ximo la gr\u00e1fica que no se disparasen las temperaturas, y nuestros miedos eran infundados, con una temperatura m\u00e1xima de 71\u00baC y todo ello con un nivel de funcionamiento de los ventiladores casi inapreciable.<\/p>\n<p>El consumo de energ\u00eda ha sido elevado, de 311W, por lo que para acompa\u00f1ar adecuadamente a esta gr\u00e1fica te recomendamos al menos de una gr\u00e1fica de 650W para no tener sustos futuros por cuelgues por falta de alimentaci\u00f3n, aunque para curarnos en salud una fuente de 750W no es nada descabellada.<\/p>\n<p>Mediante la funci\u00f3n OC de MSI Afterburner, pudimos subir la frecuencia m\u00e1xima del n\u00facleo de la gr\u00e1fica +150 Mhz y 800 Mhz las memorias de forma estable, lo que se tradujo en +700 puntos en 3D Mark y 2-3 frames en benchs.<\/p>\n<p>Por \u00faltimo nos vamos al precio, actualmente es ya dif\u00edcil de encontrar y entre las tiendas online la hemos visto en Coolmod a unos descabellados <a href=\"https:\/\/www.coolmod.com\/msi-geforce-rtx-2080-ti-gaming-x-trio-11gb-gddr6-tarjeta-grafica-precio\" target=\"_blank\" rel=\"nofollow noopener\">1274 euros<\/a> y decimos descabellados pues es una gr\u00e1fica que ya tiene su sustituta de la mano de la nueva RTX 3070X, una nueva gr\u00e1fica que promete aumentar las prestaciones al menos un 20% y que podemos encontrar por menos de 800 euros hoy en dia, a pesar de encontrarlas con cuentagotas, por lo que este modelo queda a pesar de sus virtudes en tierra de nadie, aunque es una muy buena opci\u00f3n si la consigues en el mercado de segunda mano a un precio razonable.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-53847\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Oro-90.png\" alt=\"\" width=\"300\" height=\"200\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p>[joomdev-wpc-pros-cons disable_title=\u00bbno\u00bb wpc_style=\u00bbwppc-view1&#8243; title_tag=\u00bbH3&#8243; title=\u00bbMSI GEFORCE RTX 2080 TI GAMING X TRIO\u00bb pros_title=\u00bbA FAVOR\u00bb cons_title=\u00bbEN CONTRA\u00bb button_text=\u00bbGet it now\u00bb disable_button=\u00bbno\u00bb button_link=\u00bb\u00bb button_link_target=\u00bb_SELF\u00bb button_rel_attr=\u00bbdofollow\u00bb verdict_text=\u00bbEl modelo MSI Geforce RTX 2080 TI Gaming X Trio ofrece unas prestaciones a\u00fan soberbias incluso en resoluciones 2K, pero necesita acompa\u00f1arse de un procesador realmente potente para no crear un cuello de botella. La iluminaci\u00f3n es excelente y su sistema de refrigeraci\u00f3n a la par de silencioso es muy eficaz. Es un modelo ya descatalogado que a\u00fan podemos encontrar en tiendas a un precio desorbitado, siendo una opci\u00f3n ideal para comprar en el mercado de segunda mano\u00bb][joomdev-wpc-pros]<\/p>\n<ul class=\"wp-pros-cons-list wp-pros-list\">\n<li class=\"joomdev_wpc_pro_single\">Muy buenas prestaciones<\/li>\n<li class=\"joomdev_wpc_pro_single\">Silencio de funcionamiento<\/li>\n<li class=\"joomdev_wpc_pro_single\">Temperaturas<\/li>\n<li class=\"joomdev_wpc_pro_single\">Iluminaci\u00f3n<\/li>\n<li class=\"joomdev_wpc_pro_single\">Suficiente para 2K modo Ultra<\/li>\n<\/ul>\n<p>[\/joomdev-wpc-pros][joomdev-wpc-cons]<\/p>\n<ul class=\"wp-pros-cons-list wp-cons-list\">\n<li class=\"joomdev_wpc_con_single\">Modelo ya descatalogado<\/li>\n<li class=\"joomdev_wpc_con_single\">Precio elevadisimo<\/li>\n<\/ul>\n<p>[\/joomdev-wpc-cons][\/joomdev-wpc-pros-cons]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy os traemos la review de la que es la gr\u00e1fica m\u00e1s potente de la gama RTX 2080 de MSI, con el modelo Geforce RTX 2080 TI Gaming X Trio,\u00a0 con 11 GB GDDR6 y una velocidad Boost de 1755 Mhz. &nbsp; &nbsp; Much\u00edsimas gracias a MSI por enviarnos la tarjeta gr\u00e1fica MSI Geforce RTX [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":62896,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[2365,1814],"tags":[8262,8265,8267,8266,8260,8264,8261,1491,8263],"class_list":["post-62865","post","type-post","status-publish","format-standard","has-post-thumbnail","category-reviews-hardware","category-tarjetas-graficas","tag-analisis-msi-geforce-rtx-2080-ti-gaming-x-trio","tag-caracteristicas-msi-geforce-rtx-2080-ti-gaming-x-trio","tag-comparativa-msi-geforce-rtx-2080-ti-gaming-x-trio","tag-iluminacion-msi-geforce-rtx-2080-ti-gaming-x-trio","tag-msi-geforce-rtx-2080-ti-gaming-x-trio","tag-precio-msi-geforce-rtx-2080-ti-gaming-x-trio","tag-review-msi-geforce-rtx-2080-ti-gaming-x-trio","tag-reviews-hardware-espanol","tag-unboxing-msi-geforce-rtx-2080-ti-gaming-x-trio"],"_links":{"self":[{"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/posts\/62865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/comments?post=62865"}],"version-history":[{"count":0,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/posts\/62865\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/media\/62896"}],"wp:attachment":[{"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/media?parent=62865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/categories?post=62865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/tags?post=62865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}