{"id":61391,"date":"2020-11-07T17:58:59","date_gmt":"2020-11-07T16:58:59","guid":{"rendered":"https:\/\/www.razorman.net\/reviewshardware\/?p=61391"},"modified":"2020-11-09T11:15:46","modified_gmt":"2020-11-09T10:15:46","slug":"review-msi-geforce-rtx-2080-super-gaming-x-trio","status":"publish","type":"post","link":"https:\/\/www.razorman.net\/reviewshardware\/review-msi-geforce-rtx-2080-super-gaming-x-trio\/","title":{"rendered":"Review MSI GeForce RTX 2080 SUPER Gaming X Trio"},"content":{"rendered":"<p>Hoy analizamos para vosotros una de las tarjetas gr\u00e1ficas m\u00e1s potentes de la gama 2080 de nVidia, con el modelo MSI Geforce RTX 2080 Super Gaming X Trio , con un core Boost de 1845 Mhz y una velocidad de memoria de 15.5 Gbps.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/asset.msi.com\/resize\/image\/global\/product\/product_3_20190722133238_5d354a7644999.png62405b38c58fe0f07fcef2367d8a9ba1\/600.png\" alt=\"\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p>Much\u00edsimas gracias a <strong>MSI<\/strong> por enviarnos la tarjeta gr\u00e1fica <strong>MSI GeForce RTX 2080 SUPER Gaming X Trio<\/strong>\u00a0 para la <strong>review<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/logo-msi.jpg\" alt=\"Resultado de imagen de MSI LOGO RAZORMAN\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><strong>MSI GeForce RTX 2080 SUPER Gaming X Trio<\/strong> : Caracter\u00edsticas t\u00e9cnicas<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\">MOTOR GRAFICO<\/td>\n<td style=\"width: 50%;\">NVIDIA\u00ae GeForce\u00ae RTX 2080 SUPER&#x2122;<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">BUS ESTANDARD<\/td>\n<td style=\"width: 50%;\">PCI Express x16 3.0<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">MEMORIA<\/td>\n<td style=\"width: 50%;\">8GB GDDR6 @ 15.5 Gbps . Interfaz 256 bits<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">VELOCIDAD RELOJ NUCLEO<\/td>\n<td style=\"width: 50%;\">Boost: 1845 MHz<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">PANTALLAS SOPORTADAS<\/td>\n<td style=\"width: 50%;\">HASTA 5<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">CONSUMO<\/td>\n<td style=\"width: 50%;\">250W<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">CONECTORES<\/td>\n<td style=\"width: 50%;\">DisplayPort x 3 (v1.4) \/ HDMI 2.0b x 1 \/ Type-C x1<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">FUENTE ALIMENTACION RECOMENDADA<\/td>\n<td style=\"width: 50%;\">650W . CONECTOR ALIMENTACION 8PINESX2<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">DIMENSIONES<\/td>\n<td style=\"width: 50%;\">328 x 140 x 56.5 mm<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">PESO<\/td>\n<td style=\"width: 50%;\">1531 gr<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>[nextpage title= \u00abMSI GEFORCE RTX 2080 SUPER GAMING X TRIO: UNBOXING Y ACCESORIOS\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-61393\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-1-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-1-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-1-768x510.jpg 768w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-1.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"alignright size-medium wp-image-61394\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-2-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-2-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-2-768x510.jpg 768w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-2.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La tarjeta gr\u00e1fica MSI Geforce RTX 2080 Super Gaming X Trio se presenta en una colorida caja de cart\u00f3n de fondo oscuro, donde vemos el logo del fabricante, modelo, algunas im\u00e1genes de la tarjeta y sus principales especificaciones a lo largo de los perfiles de esta caja<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-61395\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-3.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-3.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-3-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-3-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La tarjeta viene muy bien protegida: la soporta un molde de porexp\u00e1n negro y a su vez viene protegida y envuelta por una bolsa antiest\u00e1tica.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61396\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-22.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-22.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-22-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-22-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Este tipo de tarjetas para reviews pasan por muchas manos y al final van \u00abdesapareciendo\u00bb los accesorios, en nuestro caso s\u00f3lo nos ha llegado ya un soporte met\u00e1lico para la tarjeta, pues \u00e9sta pesa 1,5 kg.<\/p>\n<p>&nbsp;<\/p>\n<p>[nextpage title= \u00abMSI GEFORCE RTX 2080 SUPER GAMING X TRIO: DISE\u00d1O\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p>Realmente espectacular: una gr\u00e1fica de doble slot con unas dimensiones de 328 x 140 x 56.5 mm y un peso que llega hasta 1.5 kg, de ah\u00ed la inclusi\u00f3n de un soporte para la gr\u00e1fica.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61420\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-4-2.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-4-2.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-4-2-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-4-2-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Para garantizar una correcta refrigeraci\u00f3n incorpora 3 ventiladores Torx 3.0 de diferente tama\u00f1o com vemos todos ellos dispuestos en una atractiva carcasa de pl\u00e1stico.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61421\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-5-2.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-5-2.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-5-2-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-5-2-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Si queremos emplear un puente SLI para aumentar las prestaciones deberemos extraer previamente parte de la carcasa que cubre la tarjeta gr\u00e1fica.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61422\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-6-2.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-6-2.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-6-2-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-6-2-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Vista superior de la gr\u00e1fica, donde vemos el logo de MSI y el modelo, junto con el dragon t\u00edpico de MSI. Todo ello iluminado como veremos m\u00e1s adelante<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61423\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-7-2.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-7-2.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-7-2-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-7-2-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Realmente el gran radiador que recorre toda la gr\u00e1fica tiene un grosor muy considerable y est\u00e1 dotado de innumerables l\u00e1minas de aluminio para la disipaci\u00f3n del calor.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61424\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-8-2.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-8-2.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-8-2-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-8-2-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Dispone de doble conector de alimentaci\u00f3n de 8 pines para suministrar la energ\u00eda necesaria para el funcionamiento de la tarjeta. Su TDP anunciado por MSI es de 250W y requiere una fuente de alimentaci\u00f3n de 650W al menos para su funcionamiento.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61425\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-9-2.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-9-2.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-9-2-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-9-2-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La zona trasera de la gr\u00e1fica cuenta con un backplate trasero de aluminio cepillado que contribuye a la disipaci\u00f3n del calor.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61426\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-10-2.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-10-2.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-10-2-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-10-2-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Vista inferior de la tarjeta que nos permite intuir un gran disipador de aluminio dividido en 2 partes unidas por varios heatpipes.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61427\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-11-2.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-11-2.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-11-2-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-11-2-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>El conector a la placa base es un PCI Express 3.0<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61428\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-12-2.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-12-2.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-12-2-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-12-2-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Vista trasera de la gr\u00e1fica que nos permite ver la terminaci\u00f3n de los heatpipes.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61429\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-13-2.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-13-2.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-13-2-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-13-2-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>En el apartado de conexinoes cuente con 3 salidas DisplayPort que permiten video 8K @ 60 Hz, adem\u00e1s de una salida HDMI 2.0b para ofrecer 4K @ 60 Hz y un puerto USB Type-C, compatible con VirtualLink para la conexi\u00f3n de gafas de realidad virtual con un cable: imagen-sonido-alimentaci\u00f3n.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61430\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-14-2.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-14-2.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-14-2-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-14-2-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[nextpage title= \u00abMSI GEFORCE RTX 2080 SUPER GAMING X TRIO: PCB INTERIOR\u00bb]<\/p>\n<p>Tras retirar una buena cantidad de tornillos accedemos por fin al PCB interno, donde vemos varios pads t\u00e9rmicos para refrigerar las VRM y otros componentes electr\u00f3nicos de la gr\u00e1fica.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61431\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-15.jpg\" alt=\"\" width=\"1024\" height=\"623\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-15.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-15-300x183.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-15-768x467.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Tras retirar el frontplate met\u00e1lico encontamos un complet\u00edsimo y potente VRM de 10+2 fases para n\u00facleo+memorias.<\/p>\n<p>Podemos ver con gran precisi\u00f3n el n\u00facleo gr\u00e1fico, siendo el modelo TU104-450-A1 , que comparte con otras versiones de RTX2070\/2080. Dispone de 3072 n\u00facleos CUDA, 384 n\u00facleos Tensor y 48 n\u00facleos RT, disponiendo as\u00ed de 128-16-2 n\u00facleos m\u00e1s que la versi\u00f3n 2080 \u00aba secas\u00bb.<\/p>\n<p>La frecuencia base es de 1650 Mhz pero llega en modo Boost hasta los 1845 Mhz contando con la colaboraci\u00f3n del sistema GPU Boost 4.0.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61432\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-16.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-16.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-16-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-16-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61433\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-17.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-17.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-17-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-17-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61434\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-18.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-18.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-18-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-18-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>El gran disipador de aluminio dispone de 7 heatpipes que transportan el calor por este radiador y en contacto a trav\u00e9s de una placa con el n\u00facleo de la gr\u00e1fica.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61435\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-19.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-19.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-19-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-19-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61436\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-20.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-20.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-20-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-20-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Dispone de varios pads t\u00e9rmicos tambi\u00e9n para refrigerar los VRM de la gr\u00e1fica<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61437\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-21.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-21.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-21-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-21-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[nextpage title= \u00abMSI GEFORCE RTX 2080 SUPER GAMING X TRIO: ILUMINACION\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p>Para gestionar la iluminaci\u00f3n haremos uso de la app MSI Dragon Center que nos permite utilizar varios presets de iluminaci\u00f3n ya predefinidos y colores variados:<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61440\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.46-11.jpg\" alt=\"\" width=\"1024\" height=\"579\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.46-11.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.46-11-300x170.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.46-11-390x220.jpg 390w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.46-11-768x434.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La iluminaci\u00f3n incluye el logo de MSI superior y la gama a la cual pertenece la gr\u00e1fica, adem\u00e1s de varios Leds dispuestos en la carcasa de los ventiladores:<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61442\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/iluminacion-MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-2.jpg\" alt=\"\" width=\"1024\" height=\"573\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/iluminacion-MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-2.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/iluminacion-MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-2-300x168.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/iluminacion-MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-2-768x430.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61443\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/iluminacion-MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-3.jpg\" alt=\"\" width=\"1024\" height=\"528\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/iluminacion-MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-3.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/iluminacion-MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-3-300x155.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/iluminacion-MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-3-768x396.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[nextpage title= \u00abMSI GEFORCE RTX 2080 SUPER GAMING X TRIO: PRUEBAS DE RENDIMIENTO\u00bb]<\/p>\n<p>Este es el setup de pruebas:<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61446\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.61-9.jpg\" alt=\"\" width=\"715\" height=\"277\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.61-9.jpg 715w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.61-9-300x116.jpg 300w\" sizes=\"(max-width: 715px) 100vw, 715px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Una captura de GPU-Z<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61439\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.37-13.jpg\" alt=\"\" width=\"509\" height=\"658\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.37-13.jpg 509w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.37-13-232x300.jpg 232w\" sizes=\"(max-width: 509px) 100vw, 509px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[box type=\u00bbshadow\u00bb align=\u00bbaligncenter\u00bb class=\u00bb\u00bb width=\u00bb\u00bb]TESTS SINTETICOS[\/box]<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong><span style=\"font-size: 24pt;\">VR-MARK ORANGE ROOM<\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61447\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.62-7.jpg\" alt=\"\" width=\"700\" height=\"501\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.62-7.jpg 700w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.62-7-300x215.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong><span style=\"font-size: 24pt;\">PCMARK 10<\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61449\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.63-7.jpg\" alt=\"\" width=\"698\" height=\"507\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.63-7.jpg 698w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.63-7-300x218.jpg 300w\" sizes=\"(max-width: 698px) 100vw, 698px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 24pt;\"><strong>3DMARK<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61450\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.64-5.jpg\" alt=\"\" width=\"699\" height=\"688\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.64-5.jpg 699w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.64-5-300x295.jpg 300w\" sizes=\"(max-width: 699px) 100vw, 699px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Como esper\u00e1bamos, la RTX 2080 es muy superior a la RTX 2060 y no digamos ya a la Radeon 5500XT.<\/p>\n<p>&nbsp;<\/p>\n<p>[box type=\u00bbshadow\u00bb align=\u00bbaligncenter\u00bb class=\u00bb\u00bb width=\u00bb\u00bb]JUEGOS[\/box]<\/p>\n<p>&nbsp;<\/p>\n<p>[box type=\u00bbnote\u00bb align=\u00bbaligncenter\u00bb class=\u00bb\u00bb width=\u00bb\u00bb]ASSASIN\u00b4S CREED ODDISSEY CALIDAD MUY ALTA[\/box]<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61451\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.65-6.jpg\" alt=\"\" width=\"694\" height=\"675\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.65-6.jpg 694w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.65-6-300x292.jpg 300w\" sizes=\"(max-width: 694px) 100vw, 694px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61452\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.66-8.jpg\" alt=\"\" width=\"693\" height=\"725\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.66-8.jpg 693w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.66-8-287x300.jpg 287w\" sizes=\"(max-width: 693px) 100vw, 693px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[box type=\u00bbnote\u00bb align=\u00bbaligncenter\u00bb class=\u00bb\u00bb width=\u00bb\u00bb]CHERNOBYLITE: SETTINGS HIGH[\/box]<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61454\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.67-9.jpg\" alt=\"\" width=\"697\" height=\"721\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.67-9.jpg 697w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.67-9-290x300.jpg 290w\" sizes=\"(max-width: 697px) 100vw, 697px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61455\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.68-8.jpg\" alt=\"\" width=\"692\" height=\"683\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.68-8.jpg 692w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.68-8-300x296.jpg 300w\" sizes=\"(max-width: 692px) 100vw, 692px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[box type=\u00bbnote\u00bb align=\u00bbaligncenter\u00bb class=\u00bb\u00bb width=\u00bb\u00bb]WORLD WAR Z 2560X1440 \u2013 ALTO[\/box]<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61456\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.69-9.jpg\" alt=\"\" width=\"699\" height=\"726\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.69-9.jpg 699w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.69-9-289x300.jpg 289w\" sizes=\"(max-width: 699px) 100vw, 699px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[box type=\u00bbshadow\u00bb align=\u00bbaligncenter\u00bb class=\u00bb\u00bb width=\u00bb\u00bb]GEART TACTICS \u2013 ALTO \u2013[\/box]<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61457\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.70-8.jpg\" alt=\"\" width=\"700\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.70-8.jpg 700w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.70-8-300x291.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61458\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.71-8.jpg\" alt=\"\" width=\"689\" height=\"711\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.71-8.jpg 689w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.71-8-291x300.jpg 291w\" sizes=\"(max-width: 689px) 100vw, 689px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[box type=\u00bbshadow\u00bb align=\u00bbaligncenter\u00bb class=\u00bb\u00bb width=\u00bb\u00bb]DEUS EX MANKIND DIVIDED \u2013 CALIDAD ALTA[\/box]<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61459\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.72-7.jpg\" alt=\"\" width=\"698\" height=\"792\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.72-7.jpg 698w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.72-7-264x300.jpg 264w\" sizes=\"(max-width: 698px) 100vw, 698px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61460\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.73-8.jpg\" alt=\"\" width=\"679\" height=\"800\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.73-8.jpg 679w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.73-8-255x300.jpg 255w\" sizes=\"(max-width: 679px) 100vw, 679px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[box type=\u00bbshadow\u00bb align=\u00bbaligncenter\u00bb class=\u00bb\u00bb width=\u00bb\u00bb]GEARS 5 \u2013 CALIDAD ULTRA[\/box]<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61461\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.74-7.jpg\" alt=\"\" width=\"687\" height=\"750\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.74-7.jpg 687w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.74-7-275x300.jpg 275w\" sizes=\"(max-width: 687px) 100vw, 687px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61463\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.75-6.jpg\" alt=\"\" width=\"692\" height=\"784\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.75-6.jpg 692w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.75-6-265x300.jpg 265w\" sizes=\"(max-width: 692px) 100vw, 692px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[box type=\u00bbshadow\u00bb align=\u00bbaligncenter\u00bb class=\u00bb\u00bb width=\u00bb\u00bb]TOTAL WAR THREE KINGDOMS \u2013 CALIDAD ULTRA[\/box]<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61464\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.76-7.jpg\" alt=\"\" width=\"689\" height=\"789\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.76-7.jpg 689w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.76-7-262x300.jpg 262w\" sizes=\"(max-width: 689px) 100vw, 689px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61466\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.77-6.jpg\" alt=\"\" width=\"688\" height=\"817\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.77-6.jpg 688w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.77-6-253x300.jpg 253w\" sizes=\"(max-width: 688px) 100vw, 688px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[box type=\u00bbshadow\u00bb align=\u00bbaligncenter\u00bb class=\u00bb\u00bb width=\u00bb\u00bb]TOM CLANCY\u00b4S GHOST RECON \u2013 CALIDAD ALTO[\/box]<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61467\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.78-6.jpg\" alt=\"\" width=\"683\" height=\"818\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.78-6.jpg 683w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.78-6-250x300.jpg 250w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61468\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.79-4.jpg\" alt=\"\" width=\"685\" height=\"822\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.79-4.jpg 685w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.79-4-250x300.jpg 250w\" sizes=\"(max-width: 685px) 100vw, 685px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[box type=\u00bbshadow\u00bb align=\u00bbaligncenter\u00bb class=\u00bb\u00bb width=\u00bb\u00bb]METRO EXODUS \u2013 CALIDAD ULTRA[\/box]<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61469\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.80-7.jpg\" alt=\"\" width=\"685\" height=\"736\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.80-7.jpg 685w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.80-7-279x300.jpg 279w\" sizes=\"(max-width: 685px) 100vw, 685px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61470\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.81-9.jpg\" alt=\"\" width=\"695\" height=\"898\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.81-9.jpg 695w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.81-9-232x300.jpg 232w\" sizes=\"(max-width: 695px) 100vw, 695px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[box type=\u00bbshadow\u00bb align=\u00bbaligncenter\u00bb class=\u00bb\u00bb width=\u00bb\u00bb]SHADOW OF THE TOMB RAIDER \u2013 HIGH[\/box]<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61471\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.82-8.jpg\" alt=\"\" width=\"691\" height=\"862\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.82-8.jpg 691w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.82-8-240x300.jpg 240w\" sizes=\"(max-width: 691px) 100vw, 691px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61472\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.83-9.jpg\" alt=\"\" width=\"688\" height=\"814\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.83-9.jpg 688w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.83-9-254x300.jpg 254w\" sizes=\"(max-width: 688px) 100vw, 688px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>No hay color: en todas las mediciones la RTX 2080 apabulla a la RTX 2060 como es de esperar. La RTX 2080 nos permite jugar en 2K en calidad m\u00e1xima\/alta siempre por encima de los 60 fps.<\/p>\n<p>&nbsp;<\/p>\n<p>[nextpage title= \u00abMSI GEFORCE RTX 2080 SUPER GAMING X TRIO: CONSUMO Y TEMPERATURAS\u00bb]<\/p>\n<p>Es de esperar que una gr\u00e1fica tan potente arroje unos valores elevados tanto de temperatura m\u00e1xima como de consumo, estos han sido los valores tras haber ejecutado 3D Mark Fire Strike durante 30 minutos consecutivos, monitorizando la temperatura y consumo con HWInfo64.<\/p>\n<p>&nbsp;<\/p>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 33.3333%;\"><\/td>\n<td style=\"width: 33.3333%;\">MSI GEFORCE RTX 2080 SUPER GAMING X TRIO<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">CONSUMO<\/td>\n<td style=\"width: 33.3333%;\">348w<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">TEMPERATURA<\/td>\n<td style=\"width: 33.3333%;\">48\u00baC &#8211; IDLE<\/p>\n<p>67\u00baC-FULL<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>Para realizar overclocking a la gr\u00e1fica, hemos empleado MSI Afterburner, consiguiendo aumentar los valores de frecuencia de trabajo del core en +100Mhz y 1100 Mhz para la memoria.<\/p>\n<p>&nbsp;<\/p>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 33.3333%;\"><\/td>\n<td style=\"width: 33.3333%;\">3DMARK FIRE STRIKE<\/td>\n<td style=\"width: 33.3333%;\">SHADOW OF THE TOMB RAIDER \u2013 FULL HD<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">MSI GEFORCE RTX 2080 SUPER GAMING X TRIO<\/td>\n<td style=\"width: 33.3333%;\">24843<\/td>\n<td style=\"width: 33.3333%;\">139\/171\/258<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\"><strong>MSI GEFORCE RTX 2080 SUPER GAMING X TRIO &#8211; OVERCLOCK<\/strong><\/td>\n<td style=\"width: 33.3333%;\">26430<\/td>\n<td style=\"width: 33.3333%;\">141\/175\/271<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>Al realizar OC, le pegamos un peque\u00f1o estir\u00f3n a las ya buenas posibilidades de esta RTX 2080 Super.<\/p>\n<p>&nbsp;<\/p>\n<p>[nextpage title= \u00abMSI GEFORCE RTX 2080 SUPER GAMING X TRIO: CONCLUSIONES FINALES Y PUNTUACION\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61422\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-6-2.jpg\" alt=\"\" width=\"1024\" height=\"680\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-6-2.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-6-2-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/MSI-GEFORCE-RTX-GAMING-X-TRIO-2080-SUPER-6-2-768x510.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Hasta la aparici\u00f3n de la gama RTX 30XX de nVidia, esta RTX 2080 Super era uno de los modelos m\u00e1s potentes de nVidia, ofreciendo un buen rendimiento como ha quedado patente en nuestras pruebas permitiendo jugar a cualquier t\u00edtulo en 2K en calidad m\u00e1ximo con una gran fluidez, y todo ello con un gran silencio de funcionamiento del sistema Torx 3.0 empleado y que mantiene la tarjeta realmente muy fresca para la potencia de la misma.<\/p>\n<p>Nos ha gustado la efectiva y vistosa iluminaci\u00f3n que la hace realmente bonita, adem\u00e1s el software de configuraci\u00f3n es realmente muy sencillo de utilizar y ofrece unas buenas posibilidades.<\/p>\n<p>A dia de hoy, esta tarjeta ha quedado ya en tierra de nadie, pues su precio en PCC es de <a href=\"https:\/\/www.pccomponentes.com\/msi-geforce-rtx-2070-super-gaming-x-trio-8gb-gddr6?gclid=CjwKCAiAqJn9BRB0EiwAJ1SztZYdmhvgB2H4lUzZm6ctgwvmuh-PzAia6lqD80AF1zXGFm3zTmjhYxoC9KAQAvD_BwE&amp;\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">726 euros<\/a> un precio ya fuera de mercado, pues podemos adquirir cualquiera RTX 5070 que son realmente m\u00e1s r\u00e1pidas que este modelo por casi 200 euros menos.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-53468\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Oro-89.png\" alt=\"\" width=\"300\" height=\"200\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p>[joomdev-wpc-pros-cons disable_title=\u00bbno\u00bb wpc_style=\u00bbwppc-view1&#8243; title_tag=\u00bbH3&#8243; title=\u00bbMSI GEFORCE RTX 2080 SUPER GAMING X TRIO\u00bb pros_title=\u00bbPros\u00bb cons_title=\u00bbCons\u00bb button_text=\u00bbGet it now\u00bb disable_button=\u00bbno\u00bb button_link=\u00bb\u00bb button_link_target=\u00bb_SELF\u00bb button_rel_attr=\u00bbdofollow\u00bb verdict_text=\u00bbUna tarjeta ya desfasada con las nuevas 30XX de nVidia, pero que a\u00fan puede dar mucha guerra\u00bb][joomdev-wpc-pros]<\/p>\n<ul class=\"wp-pros-cons-list wp-pros-list\">\n<li class=\"joomdev_wpc_pro_single\">SISTEMA TORX 3.0 MUY EFECTIVO<\/li>\n<li class=\"joomdev_wpc_pro_single\">POTENCIA 2K<\/li>\n<li class=\"joomdev_wpc_pro_single\">GRAN CANTIDAD DE SALIDAS &#8211; HASTA 5 MONITORES<\/li>\n<li class=\"joomdev_wpc_pro_single\">ILUMINACION RGB<\/li>\n<\/ul>\n<p>[\/joomdev-wpc-pros][joomdev-wpc-cons]<\/p>\n<ul class=\"wp-pros-cons-list wp-cons-list\">\n<li class=\"joomdev_wpc_con_single\">PRECIO DESFASADO CON LAS NUEVAS RTX 3070<\/li>\n<\/ul>\n<p>[\/joomdev-wpc-cons][\/joomdev-wpc-pros-cons]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy analizamos para vosotros una de las tarjetas gr\u00e1ficas m\u00e1s potentes de la gama 2080 de nVidia, con el modelo MSI Geforce RTX 2080 Super Gaming X Trio , con un core Boost de 1845 Mhz y una velocidad de memoria de 15.5 Gbps. &nbsp; &nbsp; Much\u00edsimas gracias a MSI por enviarnos la tarjeta gr\u00e1fica [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":61442,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[2365,1814],"tags":[8018,8021,8022,8016,8020,8017,1491,8019],"class_list":["post-61391","post","type-post","status-publish","format-standard","has-post-thumbnail","category-reviews-hardware","category-tarjetas-graficas","tag-analisis-msi-geforce-rtx-2080-super-gaming-x-trio","tag-caracteristicas-msi-geforce-rtx-2080-super-gaming-x-trio","tag-comparativa-msi-geforce-rtx-2080-super-gaming-x-trio","tag-msi-geforce-rtx-2080-super-gaming-x-trio","tag-precio-msi-geforce-rtx-2080-super-gaming-x-trio","tag-review-msi-geforce-rtx-2080-super-gaming-x-trio","tag-reviews-hardware-espanol","tag-unboxing-msi-geforce-rtx-2080-super-gaming-x-trio"],"_links":{"self":[{"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/posts\/61391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/comments?post=61391"}],"version-history":[{"count":0,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/posts\/61391\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/media\/61442"}],"wp:attachment":[{"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/media?parent=61391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/categories?post=61391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/tags?post=61391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}