{"id":46333,"date":"2017-02-22T16:24:32","date_gmt":"2017-02-22T15:24:32","guid":{"rendered":"https:\/\/www.razorman.net\/reviewshardware\/?p=46333"},"modified":"2017-02-22T16:29:16","modified_gmt":"2017-02-22T15:29:16","slug":"review-asus-rog-geforce-gtx-oc-6-gb","status":"publish","type":"post","link":"https:\/\/www.razorman.net\/reviewshardware\/review-asus-rog-geforce-gtx-oc-6-gb\/","title":{"rendered":"Review Asus ROG Geforce GTX OC 6 GB"},"content":{"rendered":"<p>Seguimos analizando tarjetas gr\u00e1ficas de la gama ROG de ASUS que nos ha enviado para esta ocasi\u00f3n el modelo <strong>Asus ROG Geforce GTX OC 6 GB<\/strong> , con<strong> tecnolog\u00eda Pascal<\/strong> y un ligero overclock de f\u00e1brica para el m\u00e1ximo rendimiento<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Rog-Geforce-GTX-1060-OC.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-46334\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Rog-Geforce-GTX-1060-OC.jpg\" alt=\"\" width=\"500\" height=\"500\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Rog-Geforce-GTX-1060-OC.jpg 500w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Rog-Geforce-GTX-1060-OC-150x150.jpg 150w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Rog-Geforce-GTX-1060-OC-300x300.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>El sistema de refrigeraci\u00f3n <strong>DirectCU III<\/strong> con ventiladores <strong>Wing-Blade<\/strong>, ofrece el m\u00e1ximo flujo de aire y rendimiento 3 veces m\u00e1s silencioso, con <strong>ASUS Fan Connect<\/strong>, un conector de 4 contactos que permite monitorizar la temperatura de la gr\u00e1fica e iluminaci\u00f3n<strong> AURA RGB<\/strong> para personalizar la tarjeta.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Rog-Geforce-GTX-1060-OC-1.jpg\"><img decoding=\"async\" class=\"aligncenter size-large wp-image-46335\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Rog-Geforce-GTX-1060-OC-1-1024x500.jpg\" alt=\"\" width=\"800\" height=\"391\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Rog-Geforce-GTX-1060-OC-1-1024x500.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Rog-Geforce-GTX-1060-OC-1-300x146.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Rog-Geforce-GTX-1060-OC-1-768x375.jpg 768w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Rog-Geforce-GTX-1060-OC-1.jpg 1250w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Adem\u00e1s se incorporan pr\u00e1cticas apps como <strong>GPU Tweak II<\/strong>, para monitorizar y realizar overclocking sobre la tarjeta y <strong>XSPlit Gamecaster<\/strong>, para restransmitir partidas en vivo, adem\u00e1s de <strong>NVIDIA GameWorks\u2122<\/strong> que proporciona una experiencia interactiva y cinem\u00e1tica y una acci\u00f3n totalmente fluida.<\/p>\n<p>&nbsp;<\/p>\n<p>Much\u00edsimas gracias a <strong>ASUS<\/strong> por enviarnos esta tarjeta gr\u00e1fica\u00a0<strong>ASUS ROG Geforce GTX OC 6 GB<\/strong>\u00a0para la <strong>review<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/logo-asus-1024x328.png\" alt=\"\" title=\"\"><\/p>\n<p><strong>ASUS ROG Geforce GTX OC 6 GB: CARACTERISTICAS TECNICAS<\/strong><\/p>\n<p>&nbsp;<\/p>\n<ul class=\"product-spec\">\n<li><span class=\"spec-item\">Motor Gr\u00e1fico<\/span>\n<div class=\"spec-data\">NVIDIA GeForce GTX 1060<\/div>\n<\/li>\n<li><span class=\"spec-item\">Bus<\/span>\n<div class=\"spec-data\">PCI Express 3.0<\/div>\n<\/li>\n<li><span class=\"spec-item\">OpenGL<\/span>\n<div class=\"spec-data\">OpenGL\u00ae4.5<\/div>\n<\/li>\n<li><span class=\"spec-item\">Memoria de Video<\/span>\n<div class=\"spec-data\">GDDR5 6GB<\/div>\n<\/li>\n<li><span class=\"spec-item\">Frecuencia del Reloj<\/span>\n<div class=\"spec-data\">Modo OC \u2013 Reloj GPU acelerado: 1873 MHz , Reloj base GPU: 1645 MHz<br \/>\nModo Gaming (por defecto) &#8211; Reloj GPU acelerado: 1847 MHZ , Reloj base GPU: 1620 MHz<br \/>\n*El stock a la venta se encuentra configurado por defecto en modo gaming. Podr\u00e1s ajustar la gr\u00e1fica al modo OC con un simple clic en la interfaz de GPU Tweak.<\/div>\n<\/li>\n<li><span class=\"spec-item\">N\u00facleo CUDA<\/span>\n<div class=\"spec-data\">1280<\/div>\n<\/li>\n<li><span class=\"spec-item\">Frecuencia de la Memoria<\/span>\n<div class=\"spec-data\">8208 MHz<\/div>\n<\/li>\n<li><span class=\"spec-item\">Interfaz de Memoria<\/span>\n<div class=\"spec-data\">192 bits<\/div>\n<\/li>\n<li><span class=\"spec-item\">Resoluci\u00f3n<\/span>\n<div class=\"spec-data\">Max. resoluci\u00f3n digital: 7680&#215;4320<\/div>\n<\/li>\n<li><span class=\"spec-item\">Interfaz<\/span>\n<div class=\"spec-data\">Salida DVI: S\u00ed x 1 (DVI-D)<br \/>\nSalida HDMI: S\u00ed x 2 (HDMI 2.0)<br \/>\nDisplayPort : S\u00ed x 2 (Regular DP)<br \/>\nSoporte HDCP: S\u00ed<\/div>\n<\/li>\n<li><span class=\"spec-item\">Accesorios<\/span>\n<div class=\"spec-data\">2 x Tiras de Velcro ROG<\/div>\n<\/li>\n<li><span class=\"spec-item\">Conector alimentaci\u00f3n<\/span>\n<div class=\"spec-data\">1 x 8 contactos<\/div>\n<\/li>\n<li><span class=\"spec-item\">Software<\/span>\n<div class=\"spec-data\">ASUS GPU Tweak II y Driver<\/div>\n<\/li>\n<li><span class=\"spec-item\">Dimensiones<\/span>\n<div class=\"spec-data\">11.73 \u00bb x 5.28 \u00bb x 1.57 \u00bb pulgadas<br \/>\n29.8 x 13.4 x4 cm.<\/div>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[nextpage title= \u00abASUS STRIX GEFORCE GTX 1060 OC: UNBOXING Y ACCESORIOS\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p>El embalaje exterior sigue la l\u00ednea que ya vimos en su d\u00eda con el modelo <a href=\"https:\/\/www.razorman.net\/reviewshardware\/review-asus-strix-geforce-gtx-1050\/2\/\" target=\"_blank\">GTX 1050<\/a>\u00a0: una caja de cart\u00f3n de fondo oscuro, imagen de la tarjeta, logo del modelo y alguna de sus caracter\u00edsticas principales , quedando la zona trasera del embalaje para visualizar las especificaciones m\u00e1s relevantes de la tarjeta:<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-22.jpg\"><br \/>\n<\/a> <a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-1.jpg\"><img decoding=\"async\" class=\"aligncenter size-large wp-image-46337\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-1.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-1.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-1-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-1-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a> <a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46338\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-2.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-2.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-2-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-2-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Abrimos la tapa, y vemos una caja de cart\u00f3n negra con el logo del fabricante, en la cual van dispuestos los accesorios que acompa\u00f1an la tarjeta gr\u00e1fica<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46339\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-5.jpg\" alt=\"\" width=\"747\" height=\"600\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-5.jpg 747w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-5-300x241.jpg 300w\" sizes=\"(max-width: 747px) 100vw, 747px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Los accesorios incluidos son un DVD con los drivers y apps principales, tiras de velcro ROG, Manual de instrucciones e invitaci\u00f3n al juego World Waships.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46346\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-21.jpg\" alt=\"\" width=\"735\" height=\"600\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-21.jpg 735w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-21-300x245.jpg 300w\" sizes=\"(max-width: 735px) 100vw, 735px\" \/><\/p>\n<p>[nextpage title= \u00abASUS STRIX GEFORCE GTX 1060 OC: EN DETALLE\u00bb]<br \/>\n&nbsp;<br \/>\n&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-7.jpg\"><br \/>\n<\/a> <a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-8.jpg\"><br \/>\n<\/a> <a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-18.jpg\"><br \/>\n<\/a> <a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-19.jpg\"><br \/>\n<\/a>Las dimensiones de la gr\u00e1fica son de\u00a029.8 x 13.4 x4 cm., por lo que ya nos damos una idea de su tama\u00f1o. Compatible con OpenGL 4.5 , posee 6 GB de memoria DDR5 @ 8208 Mhz e interfaz de memoria 192 bits, con 1280 n\u00facleo CUDA y un ligero overclocking de f\u00e1brica de los 1645 Mhz a 1873 Mhz &#8211; Modo OC &#8211; mientras que en modo gaming sube a 1847 Mhz. Los 3 ventiladores son propios de tarjetas gr\u00e1ficas de muy alta gama. Los 3 ventiladores Cooltech funcionan con control PWM que no se ponen en funcionamiento hasta que la GPU ha alcanzado una determinada temperatura, con tecnolog\u00eda Wing-Blade de Asus, para generar un 105% m\u00e1s de presi\u00f3n est\u00e1tica de aire.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-9.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-46348\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-9.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-9.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-9-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-9-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Las salidas de la tarjeta son muy abundantes: DVI-D, 2 HDMI 2.0, 2 DisplayPort ( Regular DP) con soporte para HDCP, con una resoluci\u00f3n m\u00e1xima de\u00a07680&#215;4320<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-10.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46349\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-10.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-10.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-10-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-10-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46356\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-17.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-17.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-17-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-17-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Vista del backplate, de color negro, serigrafiado con el logo del fabricante, modelo y logo ROG<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-11.jpg\"><br \/>\n<\/a> <a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-12.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46351\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-12.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-12.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-12-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-12-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Detalle de la alimentaci\u00f3n de 8 pines . Vemos tambien parte del generoso disipador DirectCu III<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-13.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46352\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-13.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-13.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-13-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-13-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.asus.com\/es\/Graphics-Cards\/ROG-STRIX-GTX1060-O6G-GAMING\/overview\/websites\/global\/products\/J5YWnEg6d76aHVYY\/img\/cooling-pic1.jpg\" alt=\"\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Vista superior de la tarjeta , con el logo ROG y gama Strix a la que pertenece.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-14.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46353\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-14.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-14.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-14-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-14-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Conector PCI- Express 3.0<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-15.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46354\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-15.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-15.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-15-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-15-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Vista trasera de la gr\u00e1fica, con dos conectores\u00a0de 4 pines. Como explica Asus en la p\u00e1gina de referencia de la tarjeta, al jugar la temperatura de la GPU es mayor a la de la CPU, cuando los ventiladores del chasis monitorizan s\u00f3lo la temperatura de \u00e9sta \u00faltima, dando lugar a una refrigeraci\u00f3n del sistema insuficiente. l jugar, es com\u00fan que la temperatura de la GPU supere la de la CPU. A pesar de esto, los ventiladores de chasis solo monitorizan la temperatura de la CPU, lo que resulta en una refrigeraci\u00f3n del sistema insuficiente. Para solucionar este problema, las gr\u00e1ficas ROG Strix incluyen dos conectores de 4 contactos que pueden conectarse a los ventiladores de sistema.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-16.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46355\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-16.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-16.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-16-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-16-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[nextpage title= \u00abASUS STRIX GEFORCE GTX 1060 OC: SOFTWARE\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p>El software incluido est\u00e1 formado por la app ASUS GPU TweakII, la cual desde una sencilla interfaz podremos hacer overclocking con unos clics a la tarjeta gr\u00e1fica, adem\u00e1s de monitorizar diversos par\u00e1metros como el voltaje, Mhz, etc\u2026 . Destacamos GameBooster, que mediante un clic libera los procesos redundantes liberando as\u00ed recursos disponibles.<\/p>\n<div>\n<p>Dispone de varios perfiles: OC Mode, Gaming Mode, Silent Mode y My Profile, para personalizar nuestras preferencias:<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.395-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46365\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.395-2-1024x479.jpg\" alt=\"\" width=\"800\" height=\"374\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.395-2-1024x479.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.395-2-300x140.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.395-2-768x359.jpg 768w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.395-2.jpg 1033w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.397.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46367\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.397.jpg\" alt=\"\" width=\"648\" height=\"445\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.397.jpg 648w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.397-300x206.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.397-130x90.jpg 130w\" sizes=\"(max-width: 648px) 100vw, 648px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.398-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46368\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.398-1.jpg\" alt=\"\" width=\"655\" height=\"443\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.398-1.jpg 655w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.398-1-300x203.jpg 300w\" sizes=\"(max-width: 655px) 100vw, 655px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.399-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46369\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.399-2.jpg\" alt=\"\" width=\"656\" height=\"450\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.399-2.jpg 656w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.399-2-300x206.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.399-2-130x90.jpg 130w\" sizes=\"(max-width: 656px) 100vw, 656px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>En INFO, tenemos completa informaci\u00f3n sobre la tarjeta y sus caracter\u00edsticas<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.400-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46370\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.400-2.jpg\" alt=\"\" width=\"652\" height=\"447\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.400-2.jpg 652w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.400-2-300x206.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.400-2-130x90.jpg 130w\" sizes=\"(max-width: 652px) 100vw, 652px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>En Tools, disponemos de Xplit Gamecaster para guardar y retransmitir tus partidas online, adem\u00e1s de Aura, para personalizar la iluminaci\u00f3n de la tarjeta<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.401-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46371\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.401-2.jpg\" alt=\"\" width=\"653\" height=\"448\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.401-2.jpg 653w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.401-2-300x206.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.401-2-130x90.jpg 130w\" sizes=\"(max-width: 653px) 100vw, 653px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.402-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46372\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.402-2.jpg\" alt=\"\" width=\"800\" height=\"491\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.402-2.jpg 808w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.402-2-300x184.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.402-2-768x471.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Una imagen de la tarjeta con la iluminaci\u00f3n AURA. Recordemos que podemos cambiar el color, el modo de iluminaci\u00f3n &#8211; respiraci\u00f3n, est\u00e1tico, c\u00edclica &#8211; etc.. por lo que la personalizaci\u00f3n es completa con nuestro PC!<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0305.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-46382\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0305.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0305.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0305-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0305-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>[nextpage title= \u00abASUS STRIX GEFORCE GTX 1060 OC: PRUEBAS DE RENDIMIENTO\u00bb]<\/p>\n<p>&nbsp;<br \/>\n&nbsp;<\/p>\n<p>Vamos a someter a la tarjeta gr\u00e1fica tanto a test sint\u00e9ticos como a test en juegos. El equipo de pruebas estaba compuesto por estos componentes:<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>PLACA BASE: Asus X99A<\/p>\n<p>PROCESADOR: Intel Core i7 5820K<\/p>\n<p>SISTEMA OPERATIVO: WINDOWS 10<\/p>\n<p>DRIVERS: Oficiales nVidia 378.66 de fecha 14\/02\/2017<\/p>\n<p>MONITOR: ASUS FULL HD 1920X1080<\/p>\n<p>MEMORIA RAM: 16 GB DDR4 @ 2133 Mhz<\/p><\/blockquote>\n<p>&nbsp;<br \/>\n&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.393-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46363\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.393-2.jpg\" alt=\"\" width=\"388\" height=\"497\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.393-2.jpg 388w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.393-2-234x300.jpg 234w\" sizes=\"(max-width: 388px) 100vw, 388px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.394-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46364\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.394-2.jpg\" alt=\"\" width=\"381\" height=\"488\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.394-2.jpg 381w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.394-2-234x300.jpg 234w\" sizes=\"(max-width: 381px) 100vw, 381px\" \/><\/a><br \/>\n&nbsp;<br \/>\n&nbsp;<\/p>\n<h3><strong>TEST SINT\u00c9TICOS<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><strong>3D MARK 13<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Estos han sido los resultados en Time Spy, Fire Strike, Sky Diver, Cloud Gate e Ice Storm Extreme:<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.389-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46359\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.389-1-1024x529.jpg\" alt=\"\" width=\"800\" height=\"413\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.389-1-1024x529.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.389-1-300x155.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.389-1-768x397.jpg 768w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.389-1.jpg 1186w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a> <a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.390-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46360\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.390-1-1024x497.jpg\" alt=\"\" width=\"800\" height=\"388\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.390-1-1024x497.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.390-1-300x146.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.390-1-768x373.jpg 768w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.390-1.jpg 1185w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong> HEAVEN 4.0 BENCHMARK<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Settings<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.17-10.jpg\" alt=\"\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0183-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-46375\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0183-1.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0183-1.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0183-1-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0183-1-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>CINEBENCH R15<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.391-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46361\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.391-2.jpg\" alt=\"\" width=\"372\" height=\"596\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.391-2.jpg 372w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.391-2-187x300.jpg 187w\" sizes=\"(max-width: 372px) 100vw, 372px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<h3>JUEGOS<\/h3>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<h4><strong>RISE OF THE TOMB RAIDER<\/strong><\/h4>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46377\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0186-1.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0186-1.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0186-1-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0186-1-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>THIEF<\/strong><\/h4>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0184-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-46376\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0184-1.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0184-1.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0184-1-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0184-1-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h4><strong>METRO LAST LIGHT<\/strong><\/h4>\n<p>&nbsp;<\/p>\n<p><em>Settings<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.30-7.jpg\" alt=\"\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>FRAMES:\u00a0<\/strong><\/p>\n<p><strong><em>MIN &#8211; 105<\/em><\/strong><\/p>\n<p><strong><em>MAX &#8211; 120<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<h4><strong>BIOSHOCK<\/strong><\/h4>\n<p>&nbsp;<\/p>\n<p><em>Frames m\u00ednimos. 183<\/em><\/p>\n<p><em>Frames m\u00e1ximos.\u00a0496<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Bioshock_2017-02-07_02-30-49-10.jpg\" rel=\"fancybox\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-45938\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Bioshock_2017-02-07_02-30-49-10-1024x576.jpg\" sizes=\"(max-width: 800px) 100vw, 800px\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Bioshock_2017-02-07_02-30-49-10-1024x576.jpg 1024w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Bioshock_2017-02-07_02-30-49-10-300x169.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Bioshock_2017-02-07_02-30-49-10-768x432.jpg 768w\" alt=\"\" width=\"800\" height=\"450\" title=\"\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Vamos a comparar estos resultados con los que nos ofreci\u00f3 en su d\u00eda la Geforce GTX 1050<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Test sint\u00e9ticos<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.244-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-46379\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.244-3.jpg\" alt=\"\" width=\"567\" height=\"343\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.244-3.jpg 567w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.244-3-300x181.jpg 300w\" sizes=\"(max-width: 567px) 100vw, 567px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong> Juegos<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.245-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-46380\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.245-4.jpg\" alt=\"\" width=\"566\" height=\"369\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.245-4.jpg 566w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.245-4-300x196.jpg 300w\" sizes=\"(max-width: 566px) 100vw, 566px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>En ambos casos vemos que el rendimiento de la Geforce GTX 1060 es muy superior a la 1050 como era de esperar. Para resoluciones Full HD y 2K es perfecta, con suficientes frames para una fluidez total durante el juego.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Sonoridad<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-11.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-46350\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-11.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-11.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-11-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-11-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>En cuanto a sonoridad, hemos de decir que hemos quedado gratamente sorprendidos por el silencio de funcionamiento de la tarjeta, al igual que en su d\u00eda lo hizo el modelo GTX 1050, por lo que el trabajo que realizan los ventiladores Wing-Blade es sobresaliente, con unas temperaturas excelentes, de unos 26\u00baC mostrando el escritorio de Windows como pudimos comprobar y 64\u00baC en juegos.<\/p>\n<p>&nbsp;<\/p>\n<p>[nextpage title= \u00abASUS STRIX GEFORCE GTX 1060 OC: CONCLUSIONES FINALES Y PUNTUACION\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p><strong>[taq_review]<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-46384\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-3.jpg\" alt=\"\" width=\"721\" height=\"600\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-3.jpg 721w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Asus-Geforce-GTX-1060-OC-6-GB-3-300x250.jpg 300w\" sizes=\"(max-width: 721px) 100vw, 721px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La tarjeta gr\u00e1fica Asus Strix Geforce GTX 1060 OC posee un rendimiento realmente sobresaliente, con un nivel sonoro baj\u00edsimo y unas temperaturas realmente sorprendentes, gracias a sus ventiladores y su generoso radiador que aseguran unas temperaturas bajas para una tarjeta del potencial de esta Asus Strix Geforce GTX 1060.<\/p>\n<p>Esta versi\u00f3n posee un ligero OC de serie, pero no ser\u00e1 ning\u00fan problema realizar overclocking a la misma desde la propia app incluida, \u00a0ASUS GPU Tweak II , un proceso sencill\u00edsimo y al alcance de cualquier tipo de usuario.<\/p>\n<p>En nuestras pruebas la tarjeta se ha mostrado realmente muy potente, siendo muy superior al modelo 1050 previamente analizado, con una tasa de frames m\u00e1s que suficiente en cualquier resoluci\u00f3n FULL HD para una experiencia de juego m\u00e1s que satisfactoria.<\/p>\n<p>El precio de esta tarjeta Asus Strix Geforce GTX 1060 OC es de unos 335 euros en comercios online.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Platino-34.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-46385\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Platino-34.png\" alt=\"\" width=\"300\" height=\"200\" title=\"\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1>A FAVOR\u00a0<a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/positivo3.jpg\" rel=\"fancybox\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-17864\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/positivo3.jpg\" alt=\"positivo\" width=\"93\" height=\"93\" title=\"\"><\/a><\/h1>\n<p>&nbsp;<\/p>\n<ul>\n<li><span style=\"color: #008000;\"><strong>DISE\u00d1O Y PRESENTACION<\/strong><\/span><\/li>\n<li><span style=\"color: #008000;\"><b>BAJISIMA SONORIDAD<\/b><\/span><\/li>\n<li><span style=\"color: #008000;\"><strong>CALIDAD MATERIALES<\/strong><\/span><\/li>\n<li><span style=\"color: #008000;\"><strong>PRECIO\u00a0ACORDE A SU TECNOLOGIA<\/strong><\/span><\/li>\n<li><span style=\"color: #008000;\"><strong>PRESTACIONES APTAS INCLUSO 2K<\/strong><\/span><\/li>\n<li><span style=\"color: #008000;\"><b>TEMPERATURAS DE FUNCIONAMIENTO<\/b><\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1>EN CONTRA\u00a0<img decoding=\"async\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/cruz1.jpg\" alt=\"cruz\" title=\"\"><\/h1>\n<p>&nbsp;<\/p>\n<div class=\"post-cover-head\"><\/div>\n<div class=\"content post-cover\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Seguimos analizando tarjetas gr\u00e1ficas de la gama ROG de ASUS que nos ha enviado para esta ocasi\u00f3n el modelo Asus ROG Geforce GTX OC 6 GB , con tecnolog\u00eda Pascal y un ligero overclock de f\u00e1brica para el m\u00e1ximo rendimiento &nbsp; &nbsp; &nbsp; El sistema de refrigeraci\u00f3n DirectCU III con ventiladores Wing-Blade, ofrece el m\u00e1ximo [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":46384,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[2365,1814],"tags":[4645,4643,4648,4647,4644,1491,4646],"class_list":["post-46333","post","type-post","status-publish","format-standard","has-post-thumbnail","category-reviews-hardware","category-tarjetas-graficas","tag-analisis-asus-rog-geforce-gtx-oc-6-gb","tag-asus-rog-geforce-gtx-oc-6-gb","tag-caracteristicas-asus-rog-geforce-gtx-oc-6-gb","tag-precio-asus-rog-geforce-gtx-oc-6-gb","tag-review-asus-rog-geforce-gtx-oc-6-gb","tag-reviews-hardware-espanol","tag-unboxing-asus-rog-geforce-gtx-oc-6-gb"],"_links":{"self":[{"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/posts\/46333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/comments?post=46333"}],"version-history":[{"count":0,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/posts\/46333\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/media\/46384"}],"wp:attachment":[{"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/media?parent=46333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/categories?post=46333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/tags?post=46333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}