{"id":44858,"date":"2016-12-22T17:22:08","date_gmt":"2016-12-22T16:22:08","guid":{"rendered":"https:\/\/www.razorman.net\/reviewshardware\/?p=44858"},"modified":"2016-12-22T17:22:08","modified_gmt":"2016-12-22T16:22:08","slug":"review-trust-gxt-570","status":"publish","type":"post","link":"https:\/\/www.razorman.net\/reviewshardware\/review-trust-gxt-570\/","title":{"rendered":"Review Trust GXT 570"},"content":{"rendered":"<p>No solemos analizar este tipo de perif\u00e9ricos, pero Trust nos propuso la<strong> review<\/strong> de un conjunto de volante+pedales para juegos <strong>Trust GXT570<\/strong>, compatible con <strong>PC\/ PS3<\/strong>, con un tama\u00f1o compacto y <strong>13 botones configurables en el volante<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full\" src=\"http:\/\/d1b4j0je2zat9y.cloudfront.net\/21684\/product_visual1\/1920x900\/16006183\" width=\"1920\" height=\"1010\" alt=\"\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>El volante posee<strong> funci\u00f3n vibraci\u00f3n<\/strong>, \u00a0para una mejor experiencia en el juego y una<strong> rotaci\u00f3n de hasta 100\u00ba<\/strong> . El anclaje a la mesa del volante est\u00e1 garantizado por 4 grandes ventosas y la plataforma de los pedales posee varios pads antideslizamiento<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full\" src=\"http:\/\/d1b4j0je2zat9y.cloudfront.net\/21684\/product_front2\/1920x900\/16006183\" width=\"1920\" height=\"1692\" alt=\"\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>El volante es compatible con<strong>\u00a0DirectInput y XInput<\/strong>, y posee <strong>drivers compatibles para PC<\/strong> . Much\u00edsimas gracias a <strong>Trust<\/strong> por enviarnos este conjunto de volante+pedales<strong> Trust\u00a0GXT570<\/strong> para la <strong>review<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/logo-trust.png\" rel=\"fancybox\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-43793\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/logo-trust.png\" sizes=\"(max-width: 416px) 100vw, 416px\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/logo-trust.png 416w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/logo-trust-300x87.png 300w\" alt=\"logo-trust\" width=\"416\" height=\"121\" title=\"\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>CARACTERISTICAS TECNICAS<\/p>\n<p>&nbsp;<\/p>\n<table class=\"specsTable\">\n<tbody>\n<tr>\n<th class=\"tableHeader\">GENERAL<\/th>\n<td class=\"content\"><strong>N\u00famero de referencia:<\/strong><br \/>\n21684<\/td>\n<td class=\"content\"><strong>C\u00f3digo EAN:<\/strong><br \/>\n8713439216844<\/td>\n<td class=\"content\"><strong>Garant\u00eda :<\/strong><br \/>\n2\u00a0a\u00f1os<\/td>\n<\/tr>\n<tr class=\"spacer\">\n<td><\/td>\n<\/tr>\n<tr>\n<th class=\"tableHeader\">CONTENIDO DEL PAQUETE<\/th>\n<td class=\"content\">Volante de competici\u00f3n<\/td>\n<td class=\"content\">Pedales<\/td>\n<td class=\"content\">Manual del usuario<\/td>\n<td class=\"content\">Adhesivo Gaming<\/td>\n<\/tr>\n<tr class=\"spacer\">\n<td><\/td>\n<\/tr>\n<tr>\n<th class=\"tableHeader\">REQUISITOS M\u00cdNIMOS<\/th>\n<td class=\"content\">PC \/ Ordenador port\u00e1til con puerto USB<\/td>\n<td class=\"content\">Windows 10, 8, 7, Vista<\/td>\n<td class=\"content\">Consola (PS3)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>[nextpage title= \u00abTRUST GXT 570: UNBOXING Y ACCESORIOS\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p>El embalaje exterior lo conforma una atractiva caja de tonos oscuros. Se han impreso varias im\u00e1genes del volante, logo del fabricante y modelo, adem\u00e1s de las principales caracter\u00edsticas t\u00e9cnicas.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44860\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-1.jpg\" alt=\"\" width=\"768\" height=\"600\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-1.jpg 768w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-1-300x234.jpg 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a> <a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-2.jpg\"><br \/>\n<\/a> <a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44862\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-3.jpg\" alt=\"\" width=\"768\" height=\"600\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-3.jpg 768w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-3-300x234.jpg 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a> <a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44863\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-4.jpg\" alt=\"\" width=\"778\" height=\"600\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-4.jpg 778w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-4-300x231.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-4-768x592.jpg 768w\" sizes=\"(max-width: 778px) 100vw, 778px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>ACCESORIOS<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Como accesorios se incluye un folleto de instrucciones, consejos de seguridad y una pegatina de Trust Gaming<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44877\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-20.jpg\" alt=\"\" width=\"800\" height=\"586\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-20.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-20-300x220.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-20-768x563.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Detalles de los accesorios incluidos:<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44864\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-5.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-5.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-5-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-5-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a> <a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44865\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-6.jpg\" alt=\"\" width=\"800\" height=\"356\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-6.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-6-300x134.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-6-768x342.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[nextpage title= \u00abTRUST GXT 570: EN DETALLE\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p>El volante tiene unas dimensiones de\u00a020,8 x 38 x 16,4 cm para un peso de 880 gramos. El material empleado para su construcci\u00f3n es pl\u00e1stico que gracias a sus rugosidades exteriores proporciona un buen agarre. El volante es compacto y est\u00e1 abierto como vemos en las im\u00e1genes en la zona superior, girando un m\u00e1ximo de 100\u00ba<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-7.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44866\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-7.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-7.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-7-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-7-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>El volante es compatible con las plataformas PC\/PS3 , posee 13 botones configurables y es compatible con\u00a0DirectInput y XInput<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-8.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44867\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-8.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-8.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-8-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-8-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Vista lateral del volante:<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-9.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44868\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-9.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-9.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-9-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-9-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Encontramos un conector de tipo RJ-45 para la conexi\u00f3n de los pedales al volante.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44871\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-12.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-12.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-12-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-12-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>El cable de conexi\u00f3n al PC \/ PS3 es de tipo USB<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-10.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44869\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-10.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-10.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-10-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-10-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>El volante tambi\u00e9n posee 2 gatillos como vemos en la imagen<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-11.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44870\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-11.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-11.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-11-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-11-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Y se sujeta a la mesa mediante estas 3 ventosas.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-12.jpg\"><br \/>\n<\/a> <a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-13.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44872\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-13.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-13.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-13-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-13-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Detalle de los pedales, montados sobre una s\u00f3lida plataforma de pl\u00e1stico<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-15.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44873\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-15.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-15.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-15-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-15-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a> <a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-16.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44874\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-16.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-16.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-16-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-16-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La plataforma de los pedales, posee 4 pads de goma antideslizante.<\/p>\n<p>&nbsp;<br \/>\n<a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-17.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44875\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-17.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-17.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-17-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-17-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Conector de tipo RJ-45 para su conexi\u00f3n al volante.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-18.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44876\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-18.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-18.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-18-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-18-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[nextpage title= \u00abTRUST GXT 570: CONEXION Y DRIVERS\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p>Al instalar el volante al PC, este se reconoce autom\u00e1ticamente en el Panel de Control:<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.162-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44927\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.162-2.jpg\" alt=\"\" width=\"387\" height=\"160\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.162-2.jpg 387w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.162-2-300x124.jpg 300w\" sizes=\"(max-width: 387px) 100vw, 387px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Al conectarse al PC, pulsaremos durante unos 6 segundos la tecla MODE para la sincronizaci\u00f3n del Pedal\/volantes, encendi\u00e9ndose un Led azul en el volante:<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0350.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44928\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0350.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0350.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0350-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0350-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-20.jpg\"><br \/>\n<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[nextpage title= \u00abTRUST GXT 570: IMPRESIONES DE USO\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0364.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44929\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0364.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0364.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0364-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0364-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Hemos probado el kit de volantes+pedales Trust GXT 570 en el juego Dirt Rally, reconociendo el juego el volante sin problemas, teniendo que configurar las acciones habituales de aceleraci\u00f3n, freno, freno de mano, vista trasera&#8230; desde el juego. La vibraci\u00f3n del volante funciona perfectamente cuando chocamos contra alg\u00fan obst\u00e1culo, derrapar&#8230; creando una buena inmersi\u00f3n en el juego.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-8.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44867\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-8.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-8.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-8-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-8-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Ten\u00edamos cierto recelo a la hora de jugar con el volante por su peque\u00f1o tama\u00f1o, pero ciertamente tras un corto per\u00edodo de aprendizaje el manejo del juego a trav\u00e9s del volante es mucho m\u00e1s satisfactorio y con mucha mayor precisi\u00f3n que con el teclado, la respuesta de los pedales es correcta, teniendo que ejercer una presi\u00f3n adecuada para acelerar y sobretodo para frenar.<\/p>\n<p>El volante gira 100\u00ba, m\u00e1s que suficiente para girar el coche en cualquier \u00abhorquilla\u00bb del trazado ayud\u00e1ndonos del freno de mano. En cuanto a precisi\u00f3n debemos decir que es realmente sorprendente la respuesta del coche a cualquier giro del volante en cuanto a su progresividad.<\/p>\n<p>Por \u00faltimo, el aspecto que menos nos ha gustado es el apartado de la fijaci\u00f3n del volante a la mesa, confiando este agarre a 3 ventosas, que ofrecen un agarre normal, pero que ser\u00eda mucho m\u00e1s firme y s\u00f3lido mediante la t\u00edpica \u00abmordaza\u00bb de otros modelos, pero justificado la inclusi\u00f3n de estas ventosas por el precio reducido del volante.<\/p>\n<p>&nbsp;<\/p>\n<p>[nextpage title= \u00abTRUST GXT 570: CONCLUSIONES FINALES Y PUNTUACION\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p><strong>[taq_review]<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44878\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-23.jpg\" alt=\"\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-23.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-23-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Trust-GXT570-23-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Indiscutiblemente para jugar y tener la mejor impresi\u00f3n e inmersi\u00f3n en simuladores de conducci\u00f3n necesitaremos un volante como este Trust GXT 570. Su reducido tama\u00f1o no impide que el manejo sea realmente muy satisfactorio, con una buena sensibilidad de uso y buena ergonom\u00eda.<\/p>\n<p>La calidad de materiales es realmente correcta para su precio, con nada menos que 13 botones programables y funci\u00f3n vibraci\u00f3n que aumenta la sensaci\u00f3n de realismo al conducir. Es compatible con PS3<\/p>\n<p>El \u00fanico pero es la sujecci\u00f3n a la mesa mediante 3 ventosas, suficiente pero que en ocasiones se despega el conjunto de la mesa, mejor\u00e1ndose si tuviera un sistema de tipo mordaza como en otros modelos m\u00e1s caros.<\/p>\n<p>El precio de este kit de volante + pedales Trust GXT 570 es de unos 29.90 euros en comercios online.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Oro-47.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44881\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Oro-47.png\" alt=\"\" width=\"300\" height=\"200\" title=\"\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1>A FAVOR\u00a0<a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/positivo3.jpg\" rel=\"fancybox\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-17864\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/positivo3.jpg\" alt=\"positivo\" width=\"93\" height=\"93\" title=\"\"><\/a><\/h1>\n<p>&nbsp;<\/p>\n<ul>\n<li><span style=\"color: #008000;\"><strong>DISE\u00d1O Y PRESENTACION<\/strong><\/span><\/li>\n<li><span style=\"color: #008000;\"><b>CALIDAD MATERIALES<\/b><\/span><\/li>\n<li><span style=\"color: #008000;\"><strong>RELACION CALIDAD-PRECIO<\/strong><\/span><\/li>\n<li><span style=\"color: #008000;\"><b>COMPATIBLE PS3<\/b><\/span><\/li>\n<li><span style=\"color: #008000;\"><strong>FUNCION VIBRACION<\/strong><\/span><\/li>\n<li><span style=\"color: #008000;\"><b>BUENA PRECISION Y SENSIBILIDAD<\/b><\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h1>EN CONTRA\u00a0<a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/cruz1.jpg\" rel=\"fancybox\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-17865\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/cruz1.jpg\" alt=\"cruz\" width=\"93\" height=\"95\" title=\"\"><\/a><\/h1>\n<p><strong>\u2013\u00a0<span style=\"color: #ff0000;\">SUJECCION POR VENTOSAS NO DEMASIADO FIRME<\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No solemos analizar este tipo de perif\u00e9ricos, pero Trust nos propuso la review de un conjunto de volante+pedales para juegos Trust GXT570, compatible con PC\/ PS3, con un tama\u00f1o compacto y 13 botones configurables en el volante &nbsp; &nbsp; &nbsp; El volante posee funci\u00f3n vibraci\u00f3n, \u00a0para una mejor experiencia en el juego y una rotaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":44877,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[2365,4400],"tags":[4403,4407,4405,4406,4402,1491,4401,4404],"class_list":["post-44858","post","type-post","status-publish","format-standard","has-post-thumbnail","category-reviews-hardware","category-volante-y-pedales-gaming","tag-analisis-trust-gxt-570","tag-caracteristicas-trust-gxt-570","tag-imagenes-trust-gxt-570","tag-precio-trust-gxt-570","tag-review-trust-gxt-570","tag-reviews-hardware-espanol","tag-trust-gxt-570","tag-unboxing-trust-gxt-570"],"_links":{"self":[{"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/posts\/44858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/comments?post=44858"}],"version-history":[{"count":0,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/posts\/44858\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/media\/44877"}],"wp:attachment":[{"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/media?parent=44858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/categories?post=44858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/tags?post=44858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}