{"id":44499,"date":"2016-11-27T18:10:02","date_gmt":"2016-11-27T17:10:02","guid":{"rendered":"https:\/\/www.razorman.net\/reviewshardware\/?p=44499"},"modified":"2016-11-27T18:11:01","modified_gmt":"2016-11-27T17:11:01","slug":"review-icy-dock-mb981u3-1sa","status":"publish","type":"post","link":"https:\/\/www.razorman.net\/reviewshardware\/review-icy-dock-mb981u3-1sa\/","title":{"rendered":"Review ICY DOCK MB981U3-1SA"},"content":{"rendered":"<p>Hoy analizamos un componente muy pr\u00e1ctico de ICY DOCK , un <strong>dock para discos SATA de 2.5\/3.5&#8243;, compatible con discos IDE<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full\" src=\"http:\/\/www.icydock.com\/images\/201105\/1306200863412020844.jpg\" alt=\"\" width=\"675\" height=\"450\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Posee <strong>interfaz USB 3.0<\/strong> \u00a0y permite conectar un disco de 2.5\/3.5&#8243; en su ranura superior o bien desde un adaptador interno que permite tambi\u00e9n la conexi\u00f3n de discos IDE de 2.5\/3.5&#8243;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/www.icydock.com\/product\/images\/mb981u3_feature.jpg\" alt=\"\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Much\u00edsimas gracias a ICY DOCK por enviarnos\u00a0el\u00a0<strong>ICY DOCK MB981U3-1SA<\/strong> para la<strong> review<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/logo-icy-dock.jpg\" alt=\"\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p><strong>CARACTERISTICAS TECNICAS<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Icy Dock MB981U3-1SA. Interfaces de unidad de disco duro soportadas: SATA, Tama\u00f1os de disco duro soportados: 6.35 cm (2.5.3.5&#8243;). Velocidad de transferencia de datos: 5 Gbit\/s. Color del producto: Negro. Ancho: 15 cm, Profundidad: 7.97 cm, Altura: 9.2 cm. Interfaz: USB<\/p>\n<p>Caracteristicas:<br \/>\nCantidad de puertos USB 3.0: 1<br \/>\nN\u00famero de discos duros soportados: 1<br \/>\nInterfaces de unidad de disco duro soportadas: SATA<br \/>\nTama\u00f1os de disco duro soportados: 63,5, 88,9 mm (2.5, 3.5&#8243;)<br \/>\nVelocidad de transferencia de datos: 5 Gbit\/s<br \/>\nColor del producto: Negro<br \/>\nIndicadores LED: Si<br \/>\nAncho: 15 cm<br \/>\nProfundidad: 7,97 cm<br \/>\nAltura: 9,2 cm<br \/>\nPeso: 412g<br \/>\nInterfaz: USB<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>UNBOXING Y ACCESORIOS<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p>El embalaje exterior lo compone una caja de cart\u00f3n donde vemos en esta zona frontal una imagen del Dock, as\u00ed como algunas de sus caracter\u00edsticas t\u00e9cnicas<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-1.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-44505\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-1.jpg\" alt=\"icy-dock-mb981u3-1sa-1\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-1.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-1-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-1-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>En la zona trasera vemos una completa tabla de prestaciones, homologaciones y seriales.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-2.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-44506\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-2.jpg\" alt=\"icy-dock-mb981u3-1sa-2\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-2.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-2-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-2-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>ACCESORIOS<\/p>\n<p>&nbsp;<\/p>\n<p>En esta imagen vemos todos los accesorios incluidos<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44511\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-21.jpg\" alt=\"icy-dock-mb981u3-1sa-21\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-21.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-21-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-21-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Manual de instrucciones &#8211; en varios idiomas, pero no el nuestro &#8211;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44507\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-4.jpg\" alt=\"icy-dock-mb981u3-1sa-4\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-4.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-4-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-4-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Cable alargador Molex de 4 pines<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44508\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-5.jpg\" alt=\"icy-dock-mb981u3-1sa-5\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-5.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-5-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-5-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Transformador el\u00e9ctrico para la alimentaci\u00f3n del Dock<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44509\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-6.jpg\" alt=\"icy-dock-mb981u3-1sa-6\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-6.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-6-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-6-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Conector USB 3.0<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-7.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44510\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-7.jpg\" alt=\"icy-dock-mb981u3-1sa-7\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-7.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-7-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-7-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>EN DETALLE<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p>El dock tiene unas dimensiones de\u00a015 cm X 7,97 cm X \u00a09,2 cm para un peso de 412 gramos. El material de fabricaci\u00f3n es pl\u00e1stico y de buena calidad y solidez al tacto. En esta zona frontal vemos el logo del fabricante.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-8.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44512\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-8.jpg\" alt=\"icy-dock-mb981u3-1sa-8\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-8.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-8-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-8-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Desde la zona superior ( el plastico es completamente liso y brillante por lo que quedan marcadas las huellas dactilares con suma facilidad) vemos la ranura para la colocaci\u00f3n de la unidad SSD o disco 3.5&#8243; y bajo ellos el bot\u00f3n de apagado\/encendido la unidad. A la izquierda vemos un pulsador que libera la unidad conectada.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-10.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44513\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-10.jpg\" alt=\"icy-dock-mb981u3-1sa-10\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-10.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-10-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-10-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44519\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-17.jpg\" alt=\"icy-dock-mb981u3-1sa-17\" width=\"784\" height=\"600\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-17.jpg 784w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-17-300x230.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-17-768x588.jpg 768w\" sizes=\"(max-width: 784px) 100vw, 784px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Perfil del Dock<br \/>\n<a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-12.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44514\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-12.jpg\" alt=\"icy-dock-mb981u3-1sa-12\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-12.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-12-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-12-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Zona inferior, donde vemos 4 patas de goma y una pieza extra\u00edble con las conexiones f\u00edsicas.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44518\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-16.jpg\" alt=\"icy-dock-mb981u3-1sa-16\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-16.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-16-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-16-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Esta pieza extra\u00edble permite la conexi\u00f3n fuera de la unidad de discos IDE de 2.5\/3.5&#8243;, y tambi\u00e9n SATA<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-13.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44515\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-13.jpg\" alt=\"icy-dock-mb981u3-1sa-13\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-13.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-13-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-13-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a> <a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-14.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44516\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-14.jpg\" alt=\"icy-dock-mb981u3-1sa-14\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-14.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-14-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-14-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a> <a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-15.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44517\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-15.jpg\" alt=\"icy-dock-mb981u3-1sa-15\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-15.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-15-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-15-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a> <a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-16.jpg\"><br \/>\n<\/a> <a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/ICY-DOCK-MB981U3-1SA-17.jpg\"><br \/>\n<\/a><\/p>\n<blockquote><p>PRUEBAS DE RENDIMIENTO<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p>Vamos a conectar un disco de 3.5&#8243; Toshiba de 500 GB SATA 6.0 GB\/s al Dock para ver su rendimiento y despu\u00e9s comprobaremos el rendimiento conectando el mismo disco a la placa base. Para medir el rendimiento usaremos el software CrystalDiskMark<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0331.jpg\"><br \/>\n<\/a> <a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0332.jpg\"><br \/>\n<\/a> <a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0333.jpg\"><br \/>\n<\/a> <a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0334.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44525\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0334.jpg\" alt=\"dsc_0334\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0334.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0334-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0334-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: center;\">RENDIMIENTO DISCO 3.5&#8243; \u00a0CONECTADO A ICY DOCK<\/h3>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.148-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44527\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.148-4.jpg\" alt=\"screenshot-148\" width=\"393\" height=\"362\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.148-4.jpg 393w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.148-4-300x276.jpg 300w\" sizes=\"(max-width: 393px) 100vw, 393px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Obtuvimos unos valores de 195 MB\/s en Lectura secuencial y s\u00f3lo 33.84 MB\/s en escritura secuencial. Un valor de escritura secuencial este baj\u00edsimo.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: center;\">RENDIMIENTO DISCO 3.5&#8243; \u00a0CONECTADO A PLACA BASE DIRECTAMENTE<\/h3>\n<p>&nbsp;<\/p>\n<p>Al conectar el disco directamente a la placa base, vemos que los valores son pr\u00e1cticamente id\u00e9nticos en Lectura secuencial, pero no as\u00ed en escritura secuencial, alcanzando los 189.6 MB\/s, por lo que extraemos como conclusi\u00f3n que el DOCK limita mucho el rendimiento en escritura secuencial.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.149-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44528\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.149-4.jpg\" alt=\"screenshot-149\" width=\"396\" height=\"368\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.149-4.jpg 396w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/screenshot.149-4-300x279.jpg 300w\" sizes=\"(max-width: 396px) 100vw, 396px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>CONCLUSIONES FINALES Y PUNTUACION<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><strong>[taq_review]<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0335.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44526\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0335.jpg\" alt=\"dsc_0335\" width=\"800\" height=\"531\" title=\"\" srcset=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0335.jpg 800w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0335-300x199.jpg 300w, https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/DSC_0335-768x510.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>El rendimiento y precio son los puntos negativos de este dock del fabricante franc\u00e9s, pues en cuanto a dise\u00f1o, caracter\u00edsticas t\u00e9cnicas sobre el papel, calidad de materiales y practicidad son realmente muy buenas. En nuestras pruebas la escritura en la unidad conectada se ha resentido mucho, lastrando el rendimiento notablemente del disco duro.<\/p>\n<p>El precio en tiendas de este dispositivo ICY DOCK\u00a0MB981U3-1SA es de unos 75 euros<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Bronce-1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44529\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/Bronce-1.png\" alt=\"bronce\" width=\"300\" height=\"200\" title=\"\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1>A FAVOR\u00a0<a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/positivo3.jpg\" rel=\"fancybox\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-17864\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/positivo3.jpg\" alt=\"positivo\" width=\"93\" height=\"93\" title=\"\"><\/a><\/h1>\n<ul>\n<li><span style=\"color: #008000;\"><strong>DISE\u00d1O Y CALIDAD DE MATERIALES<\/strong><\/span><\/li>\n<li><span style=\"color: #008000;\"><b>PRACTICIDAD<\/b><\/span><\/li>\n<li><span style=\"color: #008000;\"><strong>COMPATIBLE DISCOS IDE<\/strong><\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h1>EN CONTRA\u00a0<a href=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/cruz1.jpg\" rel=\"fancybox\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-17865\" src=\"https:\/\/www.razorman.net\/reviewshardware\/wp-content\/uploads\/cruz1.jpg\" alt=\"cruz\" width=\"93\" height=\"95\" title=\"\"><\/a><\/h1>\n<p><span style=\"color: #ff0000;\"><strong>&#8211; PRESTACIONES MUY ESCASAS<\/strong><\/span><\/p>\n<p><span style=\"color: #ff0000;\"><strong>-PRECIO ELEVADO<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy analizamos un componente muy pr\u00e1ctico de ICY DOCK , un dock para discos SATA de 2.5\/3.5&#8243;, compatible con discos IDE &nbsp; &nbsp; &nbsp; Posee interfaz USB 3.0 \u00a0y permite conectar un disco de 2.5\/3.5&#8243; en su ranura superior o bien desde un adaptador interno que permite tambi\u00e9n la conexi\u00f3n de discos IDE de 2.5\/3.5&#8243; [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":44526,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[4352,2365],"tags":[4355,4358,4353,4359,4357,4354,1491,4356],"class_list":["post-44499","post","type-post","status-publish","format-standard","has-post-thumbnail","category-dock-disco-duro","category-reviews-hardware","tag-analisis-icy-dock-mb981u3-1sa","tag-caracteristicas-icy-dock-mb981u3-1sa","tag-icy-dock-mb981u3-1sa","tag-imagenes-icy-dock-mb981u3-1sa","tag-precio-icy-dock-mb981u3-1sa","tag-review-icy-dock-mb981u3-1sa","tag-reviews-hardware-espanol","tag-unboxing-icy-dock-mb981u3-1sa"],"_links":{"self":[{"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/posts\/44499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/comments?post=44499"}],"version-history":[{"count":0,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/posts\/44499\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/media\/44526"}],"wp:attachment":[{"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/media?parent=44499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/categories?post=44499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.razorman.net\/reviewshardware\/wp-json\/wp\/v2\/tags?post=44499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}